{"id":160513,"date":"2020-09-10T18:14:21","date_gmt":"2020-09-10T11:14:21","guid":{"rendered":"https:\/\/www.sentangsedtee.com\/?p=160513"},"modified":"2020-09-11T09:33:34","modified_gmt":"2020-09-11T02:33:34","slug":"%e0%b8%8a%e0%b8%b2%e0%b8%9a%e0%b8%b9%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%83%e0%b8%99","status":"publish","type":"post","link":"https:\/\/www.khaosod.co.th\/sentangsedtee\/featured\/article_160513","title":{"rendered":"\u0e04\u0e38\u0e13\u0e25\u0e38\u0e07\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14 \u0e15\u0e49\u0e19\u0e15\u0e33\u0e23\u0e31\u0e1a \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e34\u0e14\u0e1b\u0e31\u0e49\u0e19\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e22\u0e36\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01"},"content":{"rendered":"<h1><span style=\"font-size: 18pt;\">\u0e04\u0e38\u0e13\u0e25\u0e38\u0e07\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14 \u0e15\u0e49\u0e19\u0e15\u0e33\u0e23\u0e31\u0e1a \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e34\u0e14\u0e1b\u0e31\u0e49\u0e19\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e22\u0e36\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01<\/span><\/h1>\n<p>\u0e08\u0e32\u0e01\u0e14\u0e23\u0e32\u0e21\u0e48\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e1a\u0e39\u0e14\u0e31\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e23\u0e32\u0e22\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27 \u0e01\u0e34\u0e19\u0e1a\u0e38\u0e1f\u0e40\u0e1f\u0e48\u0e15\u0e4c \u0e41\u0e15\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e16\u0e39\u0e01\u0e23\u0e49\u0e32\u0e19\u0e02\u0e39\u0e48\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e32\u0e19\u0e40\u0e22\u0e2d\u0e30\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e1a\u0e39\u0e14\u0e31\u0e07 \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e42\u0e15\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e27\u0e48\u0e32 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e23\u0e32\u0e22\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e21\u0e32\u0e19\u0e32\u0e19 3 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e21\u0e31\u0e01\u0e08\u0e30\u0e17\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e25\u0e49\u0e27\u0e19 \u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e08\u0e36\u0e07\u0e41\u0e08\u0e49\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e02\u0e48\u0e21\u0e02\u0e39\u0e48 \u0e27\u0e48\u0e32 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e21\u0e35\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e02\u0e36\u0e49\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1a\u0e38\u0e1f\u0e40\u0e1f\u0e15\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e2d\u0e31\u0e49\u0e19 \u0e17\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e27\u0e21\u0e01\u0e38\u0e49\u0e07\u0e25\u0e49\u0e27\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e04\u0e32 549 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21 200 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e27\u0e25\u0e32\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e34\u0e21<\/p>\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e39\u0e01\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e4c\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e07\u0e48\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e2b\u0e32\u0e01\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e2d\u0e35\u0e01\u0e21\u0e38\u0e21 <span style=\"color: #0000ff;\"><strong>\u0e23\u0e49\u0e32\u0e19 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19<\/strong> <\/span>\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e08\u0e32\u0e01\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e16\u0e36\u0e07\u0e02\u0e19\u0e32\u0e14\u0e27\u0e48\u0e32 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e22\u0e2d\u0e21\u0e22\u0e37\u0e19\u0e15\u0e48\u0e2d\u0e41\u0e16\u0e27\u0e23\u0e2d\u0e04\u0e34\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e07\u0e0a\u0e34\u0e07\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e19\u0e31\u0e48\u0e07\u0e01\u0e34\u0e19\u0e0a\u0e32\u0e1a\u0e39\u0e0a\u0e34\u0e25\u0e46 \u0e43\u0e19\u0e23\u0e49\u0e32\u0e19<\/p>\n<figure id=\"attachment_160567\" aria-describedby=\"caption-attachment-160567\" style=\"width: 960px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-160567\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2020\/09\/73245043_2986164198087754_516315126076007247_n.jpg\" alt=\"\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e40\u0e1e\u0e08 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c\" width=\"960\" height=\"959\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/73245043_2986164198087754_516315126076007247_n.jpg 960w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/73245043_2986164198087754_516315126076007247_n-300x300.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/73245043_2986164198087754_516315126076007247_n-150x150.jpg 150w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/73245043_2986164198087754_516315126076007247_n-768x767.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/73245043_2986164198087754_516315126076007247_n-728x727.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/73245043_2986164198087754_516315126076007247_n-420x420.jpg 420w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-160567\" class=\"wp-caption-text\">\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e40\u0e1e\u0e08 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c<\/figcaption><\/figure>\n<p><strong><span style=\"color: #000000;\">\u0e04\u0e38\u0e13\u0e0a\u0e19\u0e34\u0e14\u0e32<\/span> <span style=\"color: #000000;\">\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e07\u0e29\u0e4c \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08<\/span><\/strong> \u0e40\u0e04\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e01\u0e31\u0e1a \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35 2558 \u0e27\u0e48\u0e32 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e02\u0e2d\u0e07 <span style=\"color: #000000;\"><strong>\u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14 \u0e1e\u0e27\u0e07\u0e1e\u0e22\u0e2d\u0e21<\/strong> <\/span>\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e35\u0e48\u0e0a\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e22\u0e49\u0e2d\u0e19\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32 6 \u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14 \u0e04\u0e37\u0e2d\u0e0a\u0e32\u0e22\u0e27\u0e31\u0e22\u0e43\u0e01\u0e25\u0e49\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e44\u0e27\u0e49\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e07\u0e1c\u0e25\u0e30\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07<\/p>\n<p>\u0e41\u0e21\u0e49\u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14\u0e08\u0e30\u0e44\u0e21\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e04\u0e23\u0e31\u0e27 \u0e41\u0e15\u0e48\u0e17\u0e27\u0e48\u0e32\u0e2b\u0e32\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e14\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e04\u0e19\u0e17\u0e35\u0e48\u0e25\u0e34\u0e49\u0e21\u0e23\u0e2a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e01\u0e19\u0e34\u0e49\u0e27\u0e2b\u0e31\u0e27\u0e41\u0e21\u0e48\u0e21\u0e37\u0e2d\u0e43\u0e2b\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e38\u0e13\u0e0a\u0e19\u0e34\u0e14\u0e32\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e0a\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32 \u0e1c\u0e25\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e2a\u0e19\u0e34\u0e22\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e40\u0e21\u0e19\u0e39\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e23\u0e2a\u0e2d\u0e23\u0e48\u0e2d\u0e22<\/p>\n<p>\u201c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e35\u0e48\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14\u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e04\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e34\u0e49\u0e21\u0e23\u0e2a\u0e40\u0e21\u0e19\u0e39\u0e43\u0e14\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e32\u0e14\u0e40\u0e14\u0e32\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e43\u0e14\u0e43\u0e2a\u0e48\u0e25\u0e07\u0e44\u0e1b\u0e1a\u0e49\u0e32\u0e07\u201d<\/p>\n<figure id=\"attachment_160569\" aria-describedby=\"caption-attachment-160569\" style=\"width: 960px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-160569\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2020\/09\/93782322_2817598501610992_2983840585145647104_n.jpg\" alt=\"\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e40\u0e1e\u0e08 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c\" width=\"960\" height=\"720\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93782322_2817598501610992_2983840585145647104_n.jpg 960w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93782322_2817598501610992_2983840585145647104_n-300x225.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93782322_2817598501610992_2983840585145647104_n-768x576.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93782322_2817598501610992_2983840585145647104_n-80x60.jpg 80w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93782322_2817598501610992_2983840585145647104_n-728x546.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93782322_2817598501610992_2983840585145647104_n-560x420.jpg 560w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-160569\" class=\"wp-caption-text\">\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e40\u0e1e\u0e08 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c<\/figcaption><\/figure>\n<p>\u0e09\u0e30\u0e19\u0e31\u0e49\u0e19 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14\u0e40\u0e2d\u0e48\u0e22\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e39\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e34\u0e2a\u0e23\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e08\u0e36\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e1e\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e04\u0e27\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23<\/p>\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e27\u0e48\u0e32\u0e17\u0e33\u0e44\u0e21\u0e08\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e21\u0e19\u0e39\u0e0a\u0e32\u0e1a\u0e39\u0e19\u0e31\u0e49\u0e19 \u0e04\u0e38\u0e13\u0e0a\u0e19\u0e34\u0e14\u0e32 \u0e40\u0e25\u0e48\u0e32\u0e27\u0e48\u0e32 \u201c\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 6 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e1a\u0e39 \u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e23\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e44\u0e21\u0e48\u0e21\u0e32\u0e01\u0e41\u0e2b\u0e48\u0e07 \u0e41\u0e15\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e1e\u0e35\u0e48\u0e0a\u0e32\u0e22\u0e01\u0e47\u0e27\u0e48\u0e32\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e35 \u0e41\u0e15\u0e48\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32\u0e1e\u0e35\u0e48\u0e0a\u0e32\u0e22\u0e17\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e31\u0e49\u0e22 \u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e17\u0e33\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e25\u0e22 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e25\u0e22 \u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e08\u0e36\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e0a\u0e34\u0e21 \u0e16\u0e36\u0e07\u0e02\u0e19\u0e32\u0e14\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e25\u0e34\u0e49\u0e21\u0e23\u0e2a\u0e15\u0e49\u0e19\u0e15\u0e33\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e15\u0e49\u0e19\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e01\u0e48\u0e2d\u0e19\u201d<\/p>\n<p>\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e25\u0e34\u0e49\u0e21\u0e23\u0e2a\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e43\u0e14\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e25\u0e07\u0e44\u0e1b\u0e1a\u0e49\u0e32\u0e07<\/p>\n<figure id=\"attachment_160570\" aria-describedby=\"caption-attachment-160570\" style=\"width: 960px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-160570\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2020\/09\/93619693_2817598421611000_8579859882918805504_n.jpg\" alt=\"\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e40\u0e1e\u0e08 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c\" width=\"960\" height=\"720\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93619693_2817598421611000_8579859882918805504_n.jpg 960w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93619693_2817598421611000_8579859882918805504_n-300x225.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93619693_2817598421611000_8579859882918805504_n-768x576.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93619693_2817598421611000_8579859882918805504_n-80x60.jpg 80w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93619693_2817598421611000_8579859882918805504_n-728x546.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/93619693_2817598421611000_8579859882918805504_n-560x420.jpg 560w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-160570\" class=\"wp-caption-text\">\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e40\u0e1e\u0e08 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c<\/figcaption><\/figure>\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e0a\u0e34\u0e21\u0e23\u0e2a\u0e0a\u0e32\u0e1a\u0e39\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e01\u0e47\u0e19\u0e33\u0e2a\u0e39\u0e48\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e17\u0e33 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e39\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e04\u0e19\u0e44\u0e17\u0e22<\/p>\n<p>1 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e49\u0e32\u0e27\u0e1c\u0e48\u0e32\u0e19 2 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e1a\u0e39\u0e04\u0e37\u0e2d \u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21\u0e0a\u0e32\u0e1a\u0e39 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 \u0e1e\u0e2d\u0e19\u0e2a\u0e36 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e2d\u0e35\u0e01 3 \u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21\u0e40\u0e15\u0e49\u0e32\u0e2b\u0e39\u0e49\u0e22\u0e35\u0e49\u0e16\u0e31\u0e48\u0e27\u0e07\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e31\u0e27\u0e44\u0e0a\u0e40\u0e17\u0e49\u0e32\u0e1c\u0e2a\u0e21\u0e1e\u0e23\u0e34\u0e01\u0e0a\u0e35\u0e49\u0e1f\u0e49\u0e32\u0e41\u0e14\u0e07 \u0e01\u0e47\u0e40\u0e02\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e17\u0e32\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e23\u0e34\u0e48\u0e21\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e49\u0e32\u0e19\u0e41\u0e23\u0e01 \u0e22\u0e48\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e0b\u0e2d\u0e22 41<\/p>\n<p>\u0e43\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32 \u0e17\u0e33\u0e40\u0e25\u0e14\u0e35\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e34\u0e14\u0e16\u0e19\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e07\u0e48\u0e32\u0e22 \u0e43\u0e01\u0e25\u0e49\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e21\u0e35\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e04\u0e27\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e15\u0e48\u0e17\u0e27\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e04\u0e37\u0e2d\u0e17\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19<\/p>\n<figure id=\"attachment_160571\" aria-describedby=\"caption-attachment-160571\" style=\"width: 960px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-160571\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2020\/09\/72485966_2404254822945364_154982099579830272_n.jpg\" alt=\"\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e40\u0e1e\u0e08 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c\" width=\"960\" height=\"960\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/72485966_2404254822945364_154982099579830272_n.jpg 960w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/72485966_2404254822945364_154982099579830272_n-300x300.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/72485966_2404254822945364_154982099579830272_n-150x150.jpg 150w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/72485966_2404254822945364_154982099579830272_n-768x768.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/72485966_2404254822945364_154982099579830272_n-728x728.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/72485966_2404254822945364_154982099579830272_n-420x420.jpg 420w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-160571\" class=\"wp-caption-text\">\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e40\u0e1e\u0e08 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c<\/figcaption><\/figure>\n<p>\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e33\u0e40\u0e25\u0e17\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e41\u0e21\u0e49\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e08\u0e38\u0e14\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e17\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e1f\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e14\u0e35 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d \u0e23\u0e2a\u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e04\u0e23\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e32<\/p>\n<p>\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e17\u0e35\u0e48\u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e1f \u0e41\u0e15\u0e48\u0e2a\u0e34\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e04\u0e37\u0e2d \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04<\/p>\n<p>\u201c\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e21\u0e32\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e08 \u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e32 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e08\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e35\u0e1a \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e27\u0e25\u0e32\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e1f\u0e40\u0e1f\u0e48\u0e15\u0e4c \u0e41\u0e21\u0e49\u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e23\u0e2d\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07 \u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e25\u0e14\u0e25\u0e07 \u0e01\u0e33\u0e44\u0e23\u0e19\u0e49\u0e2d\u0e22\u0e15\u0e32\u0e21 \u0e41\u0e15\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e0b\u0e49\u0e33 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e39\u0e01\u0e1e\u0e31\u0e19 \u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e2d\u0e01\u0e15\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d \u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u201d<\/p>\n<figure id=\"attachment_160572\" aria-describedby=\"caption-attachment-160572\" style=\"width: 1100px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-160572\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2020\/09\/61969077_2791838800857538_4903656190107451392_o.jpg\" alt=\"\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e15\u0e49\u0e19\u0e15\u0e33\u0e23\u0e31\u0e1a\" width=\"1100\" height=\"733\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/61969077_2791838800857538_4903656190107451392_o.jpg 1100w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/61969077_2791838800857538_4903656190107451392_o-300x200.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/61969077_2791838800857538_4903656190107451392_o-1024x682.jpg 1024w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/61969077_2791838800857538_4903656190107451392_o-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/61969077_2791838800857538_4903656190107451392_o-728x485.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/61969077_2791838800857538_4903656190107451392_o-630x420.jpg 630w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><figcaption id=\"caption-attachment-160572\" class=\"wp-caption-text\">\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e15\u0e49\u0e19\u0e15\u0e33\u0e23\u0e31\u0e1a<\/figcaption><\/figure>\n<p>\u0e04\u0e38\u0e13\u0e0a\u0e19\u0e34\u0e14\u0e32 \u0e22\u0e31\u0e07\u0e1a\u0e2d\u0e01\u0e16\u0e36\u0e07\u0e40\u0e04\u0e25\u0e47\u0e14 (\u0e44\u0e21\u0e48) \u0e25\u0e31\u0e1a \u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e07 \u201c\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e35\u0e48\u0e0a\u0e32\u0e22\u0e40\u0e1b\u0e34\u0e14\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e16\u0e36\u0e07 2 \u0e1b\u0e35 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e36\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01 \u0e19\u0e31\u0e49\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d 6 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e21\u0e49\u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e1a\u0e39\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e30\u0e41\u0e2a \u0e41\u0e15\u0e48\u0e27\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e32\u0e01\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e14\u0e22\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e33\u0e40\u0e25\u0e19\u0e2d\u0e01\u0e2b\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32 \u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e04\u0e19\u0e21\u0e32\u0e17\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e0b\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e2d\u0e01\u0e15\u0e48\u0e2d \u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e21\u0e32\u0e01\u0e41\u0e04\u0e48 \u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e22\u0e34\u0e19\u0e14\u0e35\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u201d<\/p>\n<p>\u0e08\u0e32\u0e01\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e08\u0e19\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e41\u0e16\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e35\u0e17\u0e48\u0e32\u0e08\u0e32\u0e07\u0e2b\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e08\u0e31\u0e1a\u0e08\u0e2d\u0e07\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e34\u0e49\u0e21\u0e23\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22<\/p>\n<figure id=\"attachment_160573\" aria-describedby=\"caption-attachment-160573\" style=\"width: 960px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-160573\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2020\/09\/60868016_2175071712530344_607098188544868352_n.jpg\" alt=\"\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c\" width=\"960\" height=\"720\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/60868016_2175071712530344_607098188544868352_n.jpg 960w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/60868016_2175071712530344_607098188544868352_n-300x225.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/60868016_2175071712530344_607098188544868352_n-768x576.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/60868016_2175071712530344_607098188544868352_n-80x60.jpg 80w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/60868016_2175071712530344_607098188544868352_n-728x546.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2020\/09\/60868016_2175071712530344_607098188544868352_n-560x420.jpg 560w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-160573\" class=\"wp-caption-text\">\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c<\/figcaption><\/figure>\n<p>\u0e23\u0e32\u0e27\u0e1b\u0e35 2556 \u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14\u0e04\u0e34\u0e14\u0e02\u0e22\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 \u0e01\u0e31\u0e1a\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e48\u0e32\u0e41\u0e23\u0e01\u0e40\u0e02\u0e49\u0e32 \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e07\u0e34\u0e19\u0e01\u0e49\u0e2d\u0e19\u0e21\u0e32\u0e27\u0e32\u0e07\u0e15\u0e23\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e2a\u0e48\u0e27\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e2b\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e2a\u0e39\u0e15\u0e23 \u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e27\u0e07\u0e41\u0e2b\u0e19 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e0b\u0e35\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e41\u0e21\u0e48\u0e44\u0e1b\u0e15\u0e25\u0e2d\u0e14\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e15\u0e48\u0e19\u0e35\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e43\u0e04\u0e23 \u0e01\u0e47\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e01\u0e31\u0e4a\u0e01<\/p>\n<p>\u0e09\u0e30\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e39\u0e15\u0e23 \u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a \u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e42\u0e14\u0e22\u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14\u0e22\u0e34\u0e19\u0e14\u0e35\u0e2a\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e23\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e0b\u0e35<\/p>\n<p>\u201c\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e04\u0e34\u0e14\u0e04\u0e48\u0e32\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e44\u0e21\u0e48\u0e04\u0e34\u0e14\u0e04\u0e48\u0e32\u0e41\u0e23\u0e01\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e01\u0e31\u0e19\u0e04\u0e37\u0e2d 10 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23\u0e02\u0e2d\u0e07\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e0b\u0e35 \u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e38\u0e2d\u0e32\u0e22\u0e38\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e41\u0e1a\u0e1a\u0e1b\u0e35\u0e15\u0e48\u0e2d\u0e1b\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 3 \u0e1b\u0e35 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e17\u0e38\u0e01\u0e04\u0e19\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e22\u0e2d\u0e14\u0e02\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e43\u0e04\u0e23\u0e42\u0e01\u0e2b\u0e01\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e44\u0e14\u0e49\u0e2a\u0e2d\u0e19\u0e2a\u0e39\u0e15\u0e23\u0e43\u0e2b\u0e49 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e23\u0e31\u0e48\u0e27\u0e44\u0e2b\u0e25 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e19\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07 \u0e41\u0e15\u0e48\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e40\u0e08\u0e2d\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23\u0e17\u0e33\u0e43\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e40\u0e25\u0e22\u201d <strong>\u0e04\u0e38\u0e13\u0e0a\u0e19\u0e34\u0e14\u0e32 <\/strong>\u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e38\u0e13\u0e25\u0e38\u0e07\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14 \u0e15\u0e49\u0e19\u0e15\u0e33\u0e23\u0e31\u0e1a \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e34\u0e14\u0e1b\u0e31\u0e49\u0e19\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e22\u0e36\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e08\u0e32\u0e01\u0e14\u0e23\u0e32\u0e21\u0e48\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e1a\u0e39\u0e14\u0e31\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e23\u0e32\u0e22\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27 \u0e01\u0e34\u0e19\u0e1a\u0e38\u0e1f\u0e40\u0e1f\u0e48\u0e15\u0e4c \u0e41\u0e15\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e16\u0e39\u0e01\u0e23\u0e49\u0e32\u0e19\u0e02\u0e39\u0e48\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e32\u0e19\u0e40\u0e22\u0e2d\u0e30\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e1a\u0e39\u0e14\u0e31\u0e07 \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e42\u0e15\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e27\u0e48\u0e32 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e23\u0e32\u0e22\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e21\u0e32\u0e19\u0e32\u0e19 3 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e21\u0e31\u0e01\u0e08\u0e30\u0e17\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e25\u0e49\u0e27\u0e19 \u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e08\u0e36\u0e07\u0e41\u0e08\u0e49\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e02\u0e48\u0e21\u0e02\u0e39\u0e48 \u0e27\u0e48\u0e32 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e21\u0e35\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e02\u0e36\u0e49\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1a\u0e38\u0e1f\u0e40\u0e1f\u0e15\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e2d\u0e31\u0e49\u0e19 \u0e17\u0e32\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e27\u0e21\u0e01\u0e38\u0e49\u0e07\u0e25\u0e49\u0e27\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e04\u0e32 549 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21 200 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e27\u0e25\u0e32\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e39\u0e01\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e4c\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e07\u0e48\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e2b\u0e32\u0e01\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e2d\u0e35\u0e01\u0e21\u0e38\u0e21 \u0e23\u0e49\u0e32\u0e19 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e08\u0e32\u0e01\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e16\u0e36\u0e07\u0e02\u0e19\u0e32\u0e14\u0e27\u0e48\u0e32 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e22\u0e2d\u0e21\u0e22\u0e37\u0e19\u0e15\u0e48\u0e2d\u0e41\u0e16\u0e27\u0e23\u0e2d\u0e04\u0e34\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e07\u0e0a\u0e34\u0e07\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e19\u0e31\u0e48\u0e07\u0e01\u0e34\u0e19\u0e0a\u0e32\u0e1a\u0e39\u0e0a\u0e34\u0e25\u0e46 \u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e04\u0e38\u0e13\u0e0a\u0e19\u0e34\u0e14\u0e32 \u0e28\u0e34\u0e23\u0e34\u0e1e\u0e07\u0e29\u0e4c \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e04\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e01\u0e31\u0e1a \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35 2558 \u0e27\u0e48\u0e32 \u0e0a\u0e32\u0e1a\u0e39 \u0e0a\u0e32\u0e1a\u0e39 \u0e19\u0e32\u0e07\u0e43\u0e19 \u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e02\u0e2d\u0e07 \u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14 \u0e1e\u0e27\u0e07\u0e1e\u0e22\u0e2d\u0e21 \u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e35\u0e48\u0e0a\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e22\u0e49\u0e2d\u0e19\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32 6 \u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e27\u0e31\u0e19\u0e40\u0e25\u0e34\u0e14 \u0e04\u0e37\u0e2d\u0e0a\u0e32\u0e22\u0e27\u0e31\u0e22\u0e43\u0e01\u0e25\u0e49\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e2d\u0e32\u0e0a<\/p>\n","protected":false},"author":21,"featured_media":160597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,850],"tags":[5685,29209,29210,29211,8011,27486,1754],"msn":[],"line":[10683],"class_list":["post-160513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-exclusive","tag-5685","tag-29209","tag-29210","tag-29211","tag-8011","tag-27486","tag-1754","line-prod"],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/posts\/160513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/comments?post=160513"}],"version-history":[{"count":0,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/posts\/160513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/media\/160597"}],"wp:attachment":[{"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/media?parent=160513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/categories?post=160513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/tags?post=160513"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/msn?post=160513"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/line?post=160513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}