{"id":301817,"date":"2026-01-11T03:50:32","date_gmt":"2026-01-10T20:50:32","guid":{"rendered":"https:\/\/www.sentangsedtee.com\/?p=301817"},"modified":"2026-02-12T16:25:21","modified_gmt":"2026-02-12T09:25:21","slug":"%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99-%e0%b8%aa%e0%b8%b9%e0%b9%88","status":"publish","type":"post","link":"https:\/\/www.khaosod.co.th\/sentangsedtee\/featured\/article_301817","title":{"rendered":"\u0e08\u0e32\u0e01\u0e23\u0e49\u0e32\u0e19\u0e40\u0e25\u0e47\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e39\u0e48 \u201c\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u201d \u0e02\u0e32\u0e22\u0e14\u0e35\u0e27\u0e31\u0e19\u0e25\u0e30 1,500 \u0e44\u0e21\u0e49\u00a0\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e41\u0e19\u0e30\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u00a0"},"content":{"rendered":"\n<p>\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07 \u201c\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u201d \u0e40\u0e21\u0e19\u0e39\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e49\u0e32\u0e02\u0e32\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e02\u0e2d\u0e07\u0e43\u0e04\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19&nbsp;<\/p>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e30\u0e1e\u0e32\u0e21\u0e32\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e14\u0e31\u0e07\u0e22\u0e48\u0e32\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e32\u0e22\u0e21\u0e32\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32 40 \u0e1b\u0e35 \u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e44\u0e21\u0e49\u0e25\u0e30 1 \u0e1a\u0e32\u0e17 \u0e01\u0e48\u0e2d\u0e19\u0e23\u0e35\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19 <strong>\u201c<a href=\"https:\/\/www.facebook.com\/naunmooping\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07<\/a>\u201d <\/strong>\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e21\u0e49\u0e08\u0e30\u0e02\u0e22\u0e31\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e22\u0e38\u0e04\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e08\u0e32\u0e01\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1e\u0e35\u0e01\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e25\u0e30 1,500 \u0e44\u0e21\u0e49&nbsp;<\/p>\n\n\n\n<p>\u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e17\u0e32\u0e22\u0e32\u0e17\u0e23\u0e38\u0e48\u0e19 2 <strong>\u0e04\u0e38\u0e13\u0e40\u0e0b\u0e1f-\u0e19\u0e20\u0e32\u0e27\u0e23\u0e23\u0e13 \u0e41\u0e01\u0e49\u0e27\u0e2a\u0e38\u0e02<\/strong> \u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e43\u0e2b\u0e49\u0e23\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e02\u0e32\u0e22\u0e14\u0e35\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35 \u0e17\u0e33\u0e0b\u0e2d\u0e2a\u0e2b\u0e21\u0e31\u0e01\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e47\u0e01\u0e0b\u0e35\u0e25\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e48\u0e07\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e44\u0e1b\u0e44\u0e01\u0e25\u0e16\u0e36\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-301832 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2025\/02\/546959387458011137-1024x768.jpg\" alt=\"\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\" class=\"wp-image-301832\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959387458011137-1024x768.jpg 1024w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959387458011137-300x225.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959387458011137-768x576.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959387458011137-1536x1152.jpg 1536w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959387458011137-2048x1536.jpg 2048w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959387458011137-80x60.jpg 80w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959387458011137-728x546.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959387458011137-560x420.jpg 560w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19<\/strong><\/h2>\n\n\n\n<p>\u0e04\u0e38\u0e13\u0e40\u0e0b\u0e1f \u0e40\u0e25\u0e48\u0e32\u0e27\u0e48\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e48\u0e2d\u0e19\u0e41\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e48\u0e2d\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e1e\u0e48\u0e2d\u0e40\u0e25\u0e22\u0e2b\u0e32\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e17\u0e33 \u0e42\u0e14\u0e22\u0e19\u0e33\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e01\u0e30\u0e17\u0e34\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e46 \u0e01\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e21\u0e32\u0e1b\u0e34\u0e49\u0e07\u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e01\u0e25\u0e49\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 5 \u0e41\u0e2b\u0e48\u0e07\u0e04\u0e37\u0e2d \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e32\u0e07\u0e15\u0e32\u0e04\u0e23\u0e39\u0e49\u0e2a\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e32\u0e07\u0e15\u0e32\u0e04\u0e23\u0e39\u0e49\u0e2a\u0e04\u0e2d\u0e19\u0e41\u0e27\u0e19\u0e17\u0e4c \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e23\u0e38\u0e13 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e23\u0e27\u0e07\u0e28\u0e32\u0e27\u0e32\u0e2a \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e19\u0e38\u0e1a\u0e32\u0e25\u0e27\u0e23\u0e23\u0e13\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e28\u0e36\u0e01\u0e29\u0e32<\/p>\n\n\n\n<p>\u201c\u0e1e\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e2b\u0e21\u0e31\u0e01\u0e2b\u0e21\u0e39\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e1b\u0e34\u0e49\u0e07\u0e02\u0e32\u0e22\u0e15\u0e2d\u0e19\u0e40\u0e0a\u0e49\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e14\u0e47\u0e01\u0e40\u0e02\u0e49\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e34\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e02\u0e32\u0e22\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e49\u0e25\u0e30 1 \u0e1a\u0e32\u0e17 \u0e2b\u0e21\u0e39\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21\u0e25\u0e30 22 \u0e1a\u0e32\u0e17 \u0e40\u0e2d\u0e32\u0e21\u0e32\u0e1b\u0e34\u0e49\u0e07\u0e14\u0e49\u0e27\u0e22\u0e40\u0e15\u0e32\u0e16\u0e48\u0e32\u0e19 \u0e02\u0e32\u0e22\u0e14\u0e35\u0e21\u0e32\u0e01\u0e46 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e41\u0e08\u0e01\u0e1f\u0e23\u0e35\u0e40\u0e25\u0e22 \u0e40\u0e14\u0e47\u0e01\u0e46 \u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e21\u0e32\u0e0b\u0e37\u0e49\u0e2d\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-301834 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2025\/02\/546959540181270644-1024x1024.jpg\" alt=\"\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\" class=\"wp-image-301834\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959540181270644-1024x1024.jpg 1024w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959540181270644-300x300.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959540181270644-150x150.jpg 150w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959540181270644-768x768.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959540181270644-1536x1536.jpg 1536w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959540181270644-2048x2048.jpg 2048w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959540181270644-728x728.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959540181270644-420x420.jpg 420w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e2b\u0e21\u0e39<\/strong><\/h2>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 <strong>\u0e04\u0e38\u0e13\u0e1e\u0e48\u0e2d\u0e40\u0e25\u0e47\u0e01-\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e41\u0e01\u0e49\u0e27\u0e2a\u0e38\u0e02<\/strong> \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15\u0e40\u0e04\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e14\u0e31\u0e07 \u0e43\u0e19\u0e41\u0e1c\u0e19\u0e01\u0e42\u0e23\u0e07\u0e06\u0e48\u0e32\u0e2b\u0e21\u0e39 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e19\u0e35\u0e49\u0e14\u0e35\u0e17\u0e38\u0e01\u0e0b\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21 <\/p>\n\n\n\n<p>\u201c\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e39\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e1b\u0e34\u0e14\u0e08\u0e32\u0e01\u0e40\u0e02\u0e35\u0e22\u0e07\u0e2b\u0e21\u0e39\u0e40\u0e08\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e39\u0e2a\u0e31\u0e19\u0e19\u0e2d\u0e01 \u0e01\u0e34\u0e42\u0e25\u0e25\u0e30 155 \u0e1a\u0e32\u0e17 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e0b\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e15\u0e22\u0e4c\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e39\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2b\u0e21\u0e39\u0e2a\u0e14\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e2d\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 5-10 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e40\u0e2d\u0e32\u0e21\u0e32\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e41\u0e0a\u0e48\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u201d<\/p>\n\n\n\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e2d\u0e30\u0e44\u0e23\u0e21\u0e32\u0e01 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e35\u0e48\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e04\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p>\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e2a\u0e48\u0e27\u0e19 1 : \u0e2b\u0e21\u0e39 5 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21<\/p>\n\n\n\n<p>\u0e01\u0e30\u0e17\u0e34 500 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e25\u0e34\u0e15\u0e23<\/p>\n\n\n\n<p>\u0e0b\u0e2d\u0e2a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a 50 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e25\u0e34\u0e15\u0e23<\/p>\n\n\n\n<p>\u0e0b\u0e35\u0e2d\u0e34\u0e4a\u0e27\u0e02\u0e32\u0e27 50 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e25\u0e34\u0e15\u0e23<\/p>\n\n\n\n<p>\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e22 50 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e25\u0e34\u0e15\u0e23<\/p>\n\n\n\n<p>\u0e40\u0e01\u0e25\u0e37\u0e2d 1 \u0e0a\u0e49\u0e2d\u0e19\u0e42\u0e15\u0e4a\u0e30<\/p>\n\n\n\n<p>\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e04\u0e23\u0e36\u0e48\u0e07\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21<\/p>\n\n\n\n<p>\u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22\u0e40\u0e21\u0e47\u0e14\u0e2a\u0e35\u0e02\u0e32\u0e27 1 \u0e0a\u0e49\u0e2d\u0e19\u0e42\u0e15\u0e4a\u0e30&nbsp;<\/p>\n\n\n\n<p>\u0e0b\u0e35\u0e2d\u0e34\u0e4a\u0e27 50 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e25\u0e34\u0e15\u0e23<\/p>\n\n\n\n<p>\u0e1c\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a 50 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e25\u0e34\u0e15\u0e23<\/p>\n\n\n\n<p>\u0e19\u0e33\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e1c\u0e2a\u0e21\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e19 \u0e2b\u0e21\u0e31\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e43\u0e2b\u0e49\u0e19\u0e33\u0e2b\u0e21\u0e39\u0e44\u0e1b\u0e41\u0e0a\u0e48\u0e2d\u0e31\u0e14\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2-3 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e34\u0e49\u0e07\u0e02\u0e32\u0e22\u0e44\u0e14\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-301835 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584-1024x768.jpg\" alt=\"\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\" class=\"wp-image-301835\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584-1024x768.jpg 1024w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584-300x225.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584-768x576.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584-1536x1151.jpg 1536w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584-80x60.jpg 80w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584-728x546.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584-560x420.jpg 560w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959489396376034-e1739267135584.jpg 1713w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e2a\u0e48\u0e07\u0e02\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/strong><\/h2>\n\n\n\n<p>\u0e04\u0e38\u0e13\u0e40\u0e0b\u0e1f \u0e40\u0e25\u0e48\u0e32\u0e27\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e22\u0e38\u0e14\u0e02\u0e32\u0e22\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e44\u0e1b 5 \u0e1b\u0e35 \u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e1e\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e42\u0e04\u0e27\u0e34\u0e14 \u0e2a\u0e48\u0e27\u0e19\u0e41\u0e21\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e30\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23 \u0e40\u0e25\u0e22\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e02\u0e32\u0e22\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e14\u0e34\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e46 \u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e32\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e15\u0e25\u0e32\u0e14\u0e1a\u0e19 \u0e08\u0e36\u0e07\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e49\u0e32\u0e19<\/p>\n\n\n\n<p>\u201c\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e2b\u0e19\u0e36\u0e48\u0e07 5 \u0e01\u0e34\u0e42\u0e25 \u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e21\u0e14\u0e40\u0e25\u0e22 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e23\u0e32\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e23\u0e35\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07 \u0e21\u0e32\u0e08\u0e32\u0e01\u0e0a\u0e37\u0e48\u0e2d <strong>\u0e04\u0e38\u0e13\u0e41\u0e21\u0e48\u0e19\u0e27\u0e25-\u0e2d\u0e23\u0e27\u0e14\u0e35\u0e20\u0e23\u0e13\u0e4c \u0e41\u0e01\u0e49\u0e27\u0e2a\u0e38\u0e02<\/strong> \u0e17\u0e35\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e41\u0e1a\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e17\u0e35\u0e48\u0e19\u0e38\u0e48\u0e21\u0e19\u0e27\u0e25 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e23\u0e32\u0e01\u0e47\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e25\u0e42\u0e01\u0e49\u0e40\u0e2d\u0e07<\/p>\n\n\n\n<p>\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e14\u0e35\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e17\u0e35\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e43\u0e2b\u0e49\u0e1e\u0e48\u0e2d \u0e44\u0e14\u0e49\u0e21\u0e32 1-2 \u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e32\u0e08\u0e30\u0e17\u0e33\u0e22\u0e31\u0e07\u0e44\u0e07\u0e14\u0e35\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e40\u0e22\u0e2d\u0e30 \u0e40\u0e25\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e17\u0e31\u0e49\u0e07 \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01 \u0e44\u0e2d\u0e08\u0e35 \u0e44\u0e25\u0e19\u0e4c \u0e15\u0e34\u0e4a\u0e01\u0e15\u0e47\u0e2d\u0e01 \u0e16\u0e48\u0e32\u0e22\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e17\u0e33\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e1e\u0e32\u0e01\u0e22\u0e4c\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e43\u0e2a\u0e48\u0e40\u0e1e\u0e25\u0e07 \u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e08\u0e19\u0e21\u0e32\u0e1a\u0e39\u0e21\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e15\u0e34\u0e4a\u0e01\u0e15\u0e47\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e0a\u0e2d\u0e1a\u0e14\u0e39\u0e04\u0e25\u0e34\u0e1b\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e44\u0e2b\u0e19 \u0e40\u0e0a\u0e48\u0e19 1 \u0e27\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07 \u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e2b\u0e21\u0e39\u0e43\u0e2b\u0e49\u0e14\u0e39 \u0e41\u0e15\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e2d\u0e4a\u0e01\u0e17\u0e35\u0e1f\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e25\u0e07\u0e01\u0e47\u0e40\u0e07\u0e35\u0e22\u0e1a\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-301838 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2025\/02\/469394191_18070135795712152_2324600850764238339_n-1024x1024.jpg\" alt=\"\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e25\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28\" class=\"wp-image-301838\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/469394191_18070135795712152_2324600850764238339_n-1024x1024.jpg 1024w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/469394191_18070135795712152_2324600850764238339_n-300x300.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/469394191_18070135795712152_2324600850764238339_n-150x150.jpg 150w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/469394191_18070135795712152_2324600850764238339_n-768x768.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/469394191_18070135795712152_2324600850764238339_n-728x728.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/469394191_18070135795712152_2324600850764238339_n-420x420.jpg 420w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/469394191_18070135795712152_2324600850764238339_n.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e25\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28<\/figcaption><\/figure>\n\n\n\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e02\u0e22\u0e32\u0e22\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e04\u0e19\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e0a\u0e48\u0e19 \u0e2e\u0e48\u0e2d\u0e07\u0e01\u0e07 \u0e14\u0e39\u0e44\u0e1a \u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e14\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e08\u0e36\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e15\u0e4c\u0e43\u0e2b\u0e49\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c<\/p>\n\n\n\n<p>\u201c\u0e40\u0e23\u0e32\u0e21\u0e35\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e04\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e31\u0e48\u0e07\u0e44\u0e1b\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e25\u0e22\u0e17\u0e33\u0e41\u0e1e\u0e47\u0e01\u0e0b\u0e35\u0e25\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e1a\u0e1a\u0e1b\u0e34\u0e49\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e1e\u0e47\u0e01 15 \u0e44\u0e21\u0e49 \u0e23\u0e32\u0e04\u0e32 225 \u0e1a\u0e32\u0e17 \u0e41\u0e1e\u0e47\u0e01 25 \u0e44\u0e21\u0e49 \u0e23\u0e32\u0e04\u0e32 325 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e14\u0e34\u0e1a \u0e41\u0e1e\u0e47\u0e01 20 \u0e44\u0e21\u0e49 \u0e23\u0e32\u0e04\u0e32 260 \u0e1a\u0e32\u0e17&nbsp;<\/p>\n\n\n\n<p>\u0e41\u0e15\u0e48\u0e1a\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e47\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32 \u0e40\u0e23\u0e32\u0e40\u0e25\u0e22\u0e17\u0e33\u0e0b\u0e2d\u0e2a\u0e2b\u0e21\u0e31\u0e01\u0e2b\u0e21\u0e39\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e02\u0e27\u0e14\u0e25\u0e30 195 \u0e1a\u0e32\u0e17 \u0e1a\u0e23\u0e23\u0e08\u0e38 750 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e25\u0e34\u0e15\u0e23 \u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e19\u0e33\u0e44\u0e1b\u0e2b\u0e21\u0e31\u0e01\u0e40\u0e2d\u0e07 \u0e1b\u0e34\u0e49\u0e07\u0e40\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e17\u0e33\u0e02\u0e32\u0e22\u0e01\u0e47\u0e0b\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a\u0e44\u0e1b\u0e2b\u0e21\u0e31\u0e01 \u0e01\u0e47\u0e08\u0e30\u0e44\u0e14\u0e49\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e2a\u0e39\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e40\u0e25\u0e22 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1f\u0e34\u0e25\u0e34\u0e1b\u0e1b\u0e34\u0e19\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e14\u0e19\u0e35\u0e40\u0e0b\u0e35\u0e22 \u0e0a\u0e2d\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e15\u0e38\u0e19 \u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e2a\u0e31\u0e48\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e25\u0e30 3 \u0e42\u0e2b\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e04\u0e19\u0e44\u0e17\u0e22\u0e01\u0e47\u0e15\u0e34\u0e14\u0e43\u0e08\u0e21\u0e32\u0e01\u0e46 \u0e1a\u0e2d\u0e01\u0e40\u0e23\u0e32\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e40\u0e25\u0e34\u0e01\u0e02\u0e32\u0e22\u0e19\u0e30\u201d<\/p>\n\n\n\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e17\u0e35\u0e48\u0e02\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e31\u0e19 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 07.00-12.00 \u0e19. \u0e41\u0e15\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e08\u0e32\u0e01\u0e14\u0e35\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 90% \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07 10% \u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e44\u0e21\u0e49\u0e25\u0e30 12 \u0e1a\u0e32\u0e17 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2b\u0e48\u0e2d\u0e25\u0e30 5 \u0e1a\u0e32\u0e17 \u0e14\u0e35\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35 \u0e44\u0e21\u0e49\u0e25\u0e30 17 \u0e1a\u0e32\u0e17 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2b\u0e48\u0e2d\u0e25\u0e30 10 \u0e1a\u0e32\u0e17<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-301833 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2025\/02\/546959539895795909-1024x1024.jpg\" alt=\"\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\" class=\"wp-image-301833\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959539895795909-1024x1024.jpg 1024w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959539895795909-300x300.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959539895795909-150x150.jpg 150w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959539895795909-768x768.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959539895795909-1536x1536.jpg 1536w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959539895795909-2048x2048.jpg 2048w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959539895795909-728x728.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/546959539895795909-420x420.jpg 420w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07<\/figcaption><\/figure>\n\n\n\n<p>\u0e2b\u0e32\u0e01\u0e19\u0e31\u0e1a\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e39\u0e14\u0e34\u0e1a\u0e2b\u0e21\u0e39\u0e2a\u0e38\u0e01\u0e17\u0e35\u0e48\u0e0b\u0e35\u0e25\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28 \u0e02\u0e32\u0e22\u0e14\u0e35\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35 \u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e27\u0e31\u0e19\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e32\u0e22\u0e44\u0e14\u0e49\u0e27\u0e31\u0e19\u0e25\u0e30 1,000 \u0e44\u0e21\u0e49\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e2a\u0e48\u0e27\u0e19\u0e27\u0e31\u0e19\u0e40\u0e2a\u0e32\u0e23\u0e4c-\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e02\u0e32\u0e22\u0e44\u0e14\u0e49 1,500 \u0e44\u0e21\u0e49\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b&nbsp;<\/p>\n\n\n\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e1a\u0e23\u0e01 \u0e1f\u0e39\u0e49\u0e14\u0e0b\u0e31\u0e1e\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e07\u0e32\u0e19\u0e1a\u0e27\u0e0a \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e32\u0e04\u0e32\u0e0a\u0e38\u0e14\u0e25\u0e30 70 \u0e1a\u0e32\u0e17&nbsp;<\/p>\n\n\n\n<p>\u201c\u0e40\u0e23\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e19\u0e40\u0e02\u0e49\u0e32\u0e22\u0e38\u0e04\u0e2a\u0e21\u0e31\u0e22\u0e44\u0e1b\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e04\u0e22\u0e21\u0e32\u0e19\u0e31\u0e48\u0e07\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e27\u0e48\u0e32\u0e23\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e44\u0e1b\u0e44\u0e01\u0e25\u0e21\u0e32\u0e01 \u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e25\u0e30 2 \u0e41\u0e2a\u0e19\u0e01\u0e27\u0e48\u0e32\u0e1a\u0e32\u0e17 \u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e31\u0e01\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e35\u0e02\u0e36\u0e49\u0e19\u0e25\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e19 \u0e40\u0e23\u0e32\u0e08\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e2a\u0e35\u0e22\u0e20\u0e32\u0e29\u0e35\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e08\u0e32\u0e01\u0e41\u0e15\u0e48\u0e01\u0e48\u0e2d\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e32\u0e44\u0e01\u0e25 \u0e41\u0e04\u0e48\u0e21\u0e35\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e43\u0e2b\u0e49\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e17\u0e33\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e01\u0e47\u0e1e\u0e2d\u0e41\u0e25\u0e49\u0e27\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-301839 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"910\" height=\"825\" src=\"https:\/\/www.sentangsedtee.com\/wp-content\/uploads\/2025\/02\/468789994_1066658818802964_7402075114840958990_n-e1739267891932.jpg\" alt=\"\u0e0b\u0e2d\u0e2a\u0e2b\u0e21\u0e31\u0e01\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\" class=\"wp-image-301839\" srcset=\"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/468789994_1066658818802964_7402075114840958990_n-e1739267891932.jpg 910w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/468789994_1066658818802964_7402075114840958990_n-e1739267891932-300x272.jpg 300w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/468789994_1066658818802964_7402075114840958990_n-e1739267891932-768x696.jpg 768w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/468789994_1066658818802964_7402075114840958990_n-e1739267891932-728x660.jpg 728w, https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-content\/uploads\/2025\/02\/468789994_1066658818802964_7402075114840958990_n-e1739267891932-463x420.jpg 463w\" sizes=\"auto, (max-width: 910px) 100vw, 910px\" \/><figcaption class=\"wp-element-caption\">\u0e0b\u0e2d\u0e2a\u0e2b\u0e21\u0e31\u0e01\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07<\/figcaption><\/figure>\n\n\n\n<p>\u0e04\u0e38\u0e13\u0e40\u0e0b\u0e1f \u0e1a\u0e2d\u0e01\u0e17\u0e34\u0e49\u0e07\u0e17\u0e49\u0e32\u0e22\u0e27\u0e48\u0e32 \u201c\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e08\u0e30\u0e04\u0e2d\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e16\u0e49\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23 \u0e17\u0e33\u0e40\u0e25\u0e22 \u0e40\u0e02\u0e32\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e34\u0e14\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e15\u0e32\u0e21\u0e22\u0e38\u0e04 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e22\u0e31\u0e07\u0e2d\u0e38\u0e14\u0e2b\u0e19\u0e38\u0e19\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07 \u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e35\u0e2d\u0e31\u0e18\u0e22\u0e32\u0e28\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e49\u0e32\u0e19\u0e21\u0e35\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e21\u0e32\u0e2d\u0e38\u0e14\u0e2b\u0e19\u0e38\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d \u0e40\u0e23\u0e32\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e21\u0e32\u0e01 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e40\u0e01\u0e34\u0e19\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e44\u0e27\u0e49\u201d<\/p>\n\n\n\n<p><strong>\u0e2b\u0e32\u0e01\u0e43\u0e04\u0e23\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e38\u0e14\u0e2b\u0e19\u0e38\u0e19\u0e41\u0e27\u0e30\u0e44\u0e1b\u0e17\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07 \u0e2d\u0e23\u0e38\u0e13\u0e2d\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e0b\u0e2d\u0e22 4 \u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e22\u0e39\u0e23\u0e2f \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e27\u0e25\u0e32 07.00-12.00 \u0e19. \u0e2b\u0e22\u0e38\u0e14\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c<\/strong><\/p>\n\n\n\n<p><strong>\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e15\u0e34\u0e4a\u0e01\u0e15\u0e47\u0e2d\u0e01 <a href=\"https:\/\/www.tiktok.com\/@naunmooping\" target=\"_blank\" rel=\"noreferrer noopener\">naunmooping<\/a><\/strong><\/p>\n\n\n\n<p><strong>\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d 11 \u0e01.\u0e1e. 2025<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07 \u201c\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u201d \u0e40\u0e21\u0e19\u0e39\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e49\u0e32\u0e02\u0e32\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e02\u0e2d\u0e07\u0e43\u0e04\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19&nbsp; \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e30\u0e1e\u0e32\u0e21\u0e32\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e14\u0e31\u0e07\u0e22\u0e48\u0e32\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e32\u0e22\u0e21\u0e32\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32 40 \u0e1b\u0e35 \u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e44\u0e21\u0e49\u0e25\u0e30 1 \u0e1a\u0e32\u0e17 \u0e01\u0e48\u0e2d\u0e19\u0e23\u0e35\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e19\u0e27\u0e25\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u201d \u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e21\u0e49\u0e08\u0e30\u0e02\u0e22\u0e31\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e22\u0e38\u0e04\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e08\u0e32\u0e01\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1e\u0e35\u0e01\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e25\u0e30 1,500 \u0e44\u0e21\u0e49&nbsp; \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e17\u0e32\u0e22\u0e32\u0e17\u0e23\u0e38\u0e48\u0e19 2 \u0e04\u0e38\u0e13\u0e40\u0e0b\u0e1f-\u0e19\u0e20\u0e32\u0e27\u0e23\u0e23\u0e13 \u0e41\u0e01\u0e49\u0e27\u0e2a\u0e38\u0e02 \u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e43\u0e2b\u0e49\u0e23\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e02\u0e32\u0e22\u0e14\u0e35\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35 \u0e17\u0e33\u0e0b\u0e2d\u0e2a\u0e2b\u0e21\u0e31\u0e01\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e47\u0e01\u0e0b\u0e35\u0e25\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e48\u0e07\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e44\u0e1b\u0e44\u0e01\u0e25\u0e16\u0e36\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e04\u0e38\u0e13\u0e40\u0e0b\u0e1f \u0e40\u0e25\u0e48\u0e32\u0e27\u0e48\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e48\u0e2d\u0e19\u0e41\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e48\u0e2d\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e1e\u0e48\u0e2d\u0e40\u0e25\u0e22\u0e2b\u0e32\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e17\u0e33 \u0e42\u0e14\u0e22\u0e19\u0e33\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e01\u0e30\u0e17\u0e34\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e46 \u0e01\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e21\u0e32\u0e1b\u0e34\u0e49\u0e07\u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e01\u0e25\u0e49\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 5 \u0e41\u0e2b\u0e48\u0e07\u0e04\u0e37\u0e2d \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e32\u0e07\u0e15\u0e32\u0e04\u0e23\u0e39\u0e49\u0e2a\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e32\u0e07\u0e15\u0e32\u0e04\u0e23\u0e39\u0e49\u0e2a\u0e04\u0e2d\u0e19\u0e41\u0e27\u0e19\u0e17\u0e4c \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e23\u0e38\u0e13 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e23\u0e27\u0e07\u0e28\u0e32\u0e27\u0e32\u0e2a \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e19\u0e38\u0e1a\u0e32\u0e25\u0e27\u0e23\u0e23\u0e13\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e28\u0e36\u0e01\u0e29\u0e32 \u201c\u0e1e\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e2b\u0e21\u0e31\u0e01\u0e2b\u0e21\u0e39\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e1b\u0e34\u0e49\u0e07\u0e02\u0e32\u0e22\u0e15\u0e2d\u0e19\u0e40\u0e0a\u0e49\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e14\u0e47\u0e01\u0e40\u0e02\u0e49\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e34\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e02\u0e32\u0e22\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e49\u0e25\u0e30 1 \u0e1a\u0e32\u0e17 \u0e2b\u0e21\u0e39\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21\u0e25\u0e30 22 \u0e1a\u0e32\u0e17 \u0e40\u0e2d\u0e32\u0e21\u0e32\u0e1b\u0e34\u0e49\u0e07\u0e14\u0e49\u0e27\u0e22\u0e40\u0e15\u0e32\u0e16\u0e48\u0e32\u0e19 \u0e02\u0e32\u0e22\u0e14\u0e35\u0e21\u0e32\u0e01\u0e46 \u0e40\u0e2b\u0e21<\/p>\n","protected":false},"author":17,"featured_media":301857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[850,2],"tags":[42982,774],"msn":[21824],"line":[],"class_list":["post-301817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exclusive","category-featured","tag-42982","tag-774","msn-exclusive"],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/posts\/301817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/comments?post=301817"}],"version-history":[{"count":9,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/posts\/301817\/revisions"}],"predecessor-version":[{"id":322026,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/posts\/301817\/revisions\/322026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/media\/301857"}],"wp:attachment":[{"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/media?parent=301817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/categories?post=301817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/tags?post=301817"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/msn?post=301817"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/sentangsedtee\/wp-json\/wp\/v2\/line?post=301817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}