{"id":245627,"date":"2025-07-24T19:53:03","date_gmt":"2025-07-24T12:53:03","guid":{"rendered":"https:\/\/www.technologychaoban.com\/?p=245627"},"modified":"2025-07-24T19:55:41","modified_gmt":"2025-07-24T12:55:41","slug":"%e0%b8%ab%e0%b8%99%e0%b8%b8%e0%b9%88%e0%b8%a1%e0%b8%82%e0%b8%ad%e0%b8%99%e0%b9%81%e0%b8%81%e0%b9%88%e0%b8%99-%e0%b8%9e%e0%b8%b6%e0%b9%88%e0%b8%87%e0%b8%95%e0%b8%99%e0%b9%80%e0%b8%ad%e0%b8%87-%e0%b9%83","status":"publish","type":"post","link":"https:\/\/www.khaosod.co.th\/technologychaoban\/techno\/plants-vegetables-fruit\/article_245627","title":{"rendered":"\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e1e\u0e36\u0e48\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a 30 : 30 : 30 : 10"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e38\u0e19\u0e40\u0e14\u0e34\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e08\u0e36\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32 \u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e0a\u0e19\u0e1a\u0e17\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e22\u0e40\u0e22\u0e32\u0e27\u0e4c&nbsp;&nbsp; <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e40\u0e02\u0e15\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27<\/strong> \u0e2b\u0e23\u0e37\u0e2d <strong>\u0e1e\u0e35\u0e48\u0e19\u0e34\u0e14<\/strong> \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 187 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e1a\u0e49\u0e32\u0e19\u0e01\u0e07\u0e01\u0e25\u0e32\u0e07 \u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e19\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c 081-934-9411 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e35\u0e48\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e44\u0e14\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e41\u0e25\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e21\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e22\u0e2d\u0e22\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e21\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e35 2545-2546<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized wp-image-245635 size-large\"><img decoding=\"async\" width=\"877\" height=\"1024\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2023\/03\/8-8-877x1024.png\" alt=\"\" class=\"wp-image-245635\" style=\"width:1049px;height:auto\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/8-8-877x1024.png 877w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/8-8-257x300.png 257w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/8-8-768x897.png 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/8-8-696x813.png 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/8-8-1068x1247.png 1068w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/8-8-360x420.png 360w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/8-8.png 1108w\" sizes=\"(max-width: 877px) 100vw, 877px\" \/><figcaption class=\"wp-element-caption\">\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e40\u0e02\u0e15\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27 \u0e2b\u0e23\u0e37\u0e2d \u0e1e\u0e35\u0e48\u0e19\u0e34\u0e14<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e44\u0e14\u0e49\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e36\u0e48\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e44\u0e21\u0e48\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e47\u0e08\u0e30\u0e23\u0e48\u0e2d\u0e22\u0e2b\u0e23\u0e2d\u0e41\u0e25\u0e30\u0e2b\u0e21\u0e14\u0e44\u0e1b\u0e44\u0e23\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1b\u0e38\u0e4b\u0e22\u0e2b\u0e21\u0e31\u0e01\u0e17\u0e35\u0e48\u0e1e\u0e35\u0e48\u0e19\u0e34\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e22\u0e32\u0e06\u0e48\u0e32\u0e41\u0e21\u0e25\u0e07\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0e27\u0e34\u0e18\u0e35\u0e17\u0e33\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e31\u0e01\u0e44\u0e25\u0e48\u0e41\u0e21\u0e25\u0e07\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0e43\u0e1a\u0e2a\u0e30\u0e40\u0e14\u0e32\u0e04\u0e23\u0e36\u0e48\u0e07\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21<\/li>\n\n\n\n<li>\u0e43\u0e1a\u0e22\u0e32\u0e2a\u0e39\u0e1a 2 \u0e2b\u0e48\u0e2d \u0e2b\u0e48\u0e2d\u0e25\u0e30 15 \u0e1a\u0e32\u0e17<\/li>\n\n\n\n<li>\u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39 2 \u0e02\u0e27\u0e14 \u0e02\u0e27\u0e14\u0e25\u0e30 700 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e01\u0e23\u0e31\u0e21 \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e02\u0e27\u0e14\u0e25\u0e30 12 \u0e1a\u0e32\u0e17<\/li>\n\n\n\n<li>\u0e40\u0e2b\u0e25\u0e49\u0e32\u0e02\u0e32\u0e27\u0e02\u0e27\u0e14\u0e40\u0e25\u0e47\u0e01\u0e23\u0e32\u0e04\u0e32 70-80 \u0e1a\u0e32\u0e17<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e31\u0e1a\u0e43\u0e1a\u0e2a\u0e30\u0e40\u0e14\u0e32\u0e41\u0e25\u0e49\u0e27\u0e15\u0e49\u0e21\u0e1e\u0e2d\u0e17\u0e48\u0e27\u0e21 \u0e19\u0e49\u0e33\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1 \u0e25\u0e34\u0e15\u0e23 \u0e15\u0e49\u0e21\u0e19\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 5-6 \u0e19\u0e32\u0e17\u0e35 \u0e22\u0e01\u0e25\u0e07\u0e41\u0e25\u0e49\u0e27<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e1c\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39 \u0e40\u0e2b\u0e25\u0e49\u0e32\u0e02\u0e32\u0e27 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e2b\u0e21\u0e31\u0e01\u0e43\u0e2a\u0e48\u0e16\u0e31\u0e07\u0e44\u0e27\u0e49 2 \u0e04\u0e37\u0e19 (48 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07) \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e01\u0e23\u0e2d\u0e07\u0e40\u0e2d\u0e32\u0e41\u0e15\u0e48\u0e19\u0e49\u0e33\u0e40\u0e01\u0e47\u0e1a\u0e43\u0e2a\u0e48\u0e02\u0e27\u0e14 \u0e19\u0e49\u0e33\u0e2b\u0e21\u0e31\u0e01 1 \u0e02\u0e27\u0e14 \u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e0a\u0e49\u0e44\u0e1b\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e08\u0e19\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2b\u0e21\u0e14 \u0e43\u0e0a\u0e49\u0e01\u0e31\u0e19\u0e41\u0e21\u0e25\u0e07\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e40\u0e1e\u0e25\u0e35\u0e49\u0e22\u0e41\u0e1b\u0e49\u0e07 \u0e21\u0e14\u0e07\u0e48\u0e32\u0e21 \u0e21\u0e14\u0e04\u0e31\u0e19\u0e44\u0e1f \u0e41\u0e21\u0e25\u0e07 \u0e41\u0e21\u0e25\u0e07\u0e2b\u0e27\u0e35\u0e48\u0e02\u0e32\u0e27<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e08\u0e30\u0e44\u0e14\u0e49\u0e19\u0e49\u0e33\u0e22\u0e32\u0e2b\u0e21\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2 \u0e25\u0e34\u0e15\u0e23 \u0e17\u0e22\u0e2d\u0e22\u0e43\u0e0a\u0e49\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e25\u0e30 2 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e2a\u0e32\u0e23 \u0e40\u0e19\u0e49\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1e\u0e36\u0e48\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e33\u0e2b\u0e25\u0e31\u0e07\u0e25\u0e32\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e21\u0e32 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e15\u0e48\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e0b\u0e37\u0e49\u0e2d \u0e21\u0e35\u0e01\u0e34\u0e19\u0e21\u0e35\u0e43\u0e0a\u0e49 \u0e21\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e04\u0e48\u0e2d\u0e22\u0e02\u0e32\u0e22 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e08\u0e33\u0e19\u0e27\u0e19 50 \u0e15\u0e31\u0e27 \u0e40\u0e01\u0e47\u0e1a\u0e44\u0e02\u0e48\u0e44\u0e14\u0e49\u0e27\u0e31\u0e19\u0e25\u0e30 30 \u0e1f\u0e2d\u0e07 \u0e44\u0e01\u0e48 1 \u0e23\u0e38\u0e48\u0e19\u0e2d\u0e32\u0e22\u0e38 2 \u0e1b\u0e35 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e44\u0e02\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e31\u0e27\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a\u0e25\u0e30 300 \u0e1a\u0e32\u0e17 \u0e25\u0e07\u0e17\u0e38\u0e19\u0e08\u0e23\u0e34\u0e07\u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a\u0e25\u0e30 500 \u0e1a\u0e32\u0e17 \u0e44\u0e01\u0e48 50 \u0e15\u0e31\u0e27 \u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a\u0e25\u0e30 1 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e27\u0e48\u0e32\u0e08\u0e30\u0e02\u0e22\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e16\u0e36\u0e07 200 \u0e15\u0e31\u0e27 \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e15\u0e2d\u0e19\u0e41\u0e23\u0e01\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e44\u0e01\u0e48\u0e40\u0e04\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e44\u0e02\u0e48\u0e01\u0e47\u0e08\u0e30\u0e25\u0e14\u0e25\u0e07 \u0e01\u0e47\u0e08\u0e30\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e31\u0e48\u0e07\u0e41\u0e21\u0e48\u0e44\u0e01\u0e48\u0e21\u0e32 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e08\u0e30\u0e21\u0e35\u0e22\u0e32 \u0e01\u0e47\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32 \u0e40\u0e02\u0e32\u0e01\u0e47\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e14\u0e39\u0e41\u0e25\u0e40\u0e1b\u0e47\u0e19<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized wp-image-245631 size-large\"><img decoding=\"async\" width=\"959\" height=\"1024\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2023\/03\/4-9-959x1024.png\" alt=\"\" class=\"wp-image-245631\" style=\"width:1049px;height:auto\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/4-9-959x1024.png 959w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/4-9-281x300.png 281w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/4-9-768x820.png 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/4-9-696x743.png 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/4-9-1068x1140.png 1068w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/4-9-393x420.png 393w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/4-9.png 1108w\" sizes=\"(max-width: 959px) 100vw, 959px\" \/><figcaption class=\"wp-element-caption\">\u0e44\u0e01\u0e48\u0e44\u0e02\u0e48 50 \u0e15\u0e31\u0e27\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0e02\u0e49\u0e2d\u0e14\u0e35<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e34\u0e49\u0e07\u0e40\u0e27\u0e25\u0e32\u0e43\u0e2b\u0e49\u0e2a\u0e39\u0e0d\u0e40\u0e1b\u0e25\u0e48\u0e32<\/li>\n\n\n\n<li>\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e34\u0e08\u0e27\u0e31\u0e15\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e02\u0e32\u0e22\u0e44\u0e02\u0e48\u0e44\u0e14\u0e49\u0e27\u0e31\u0e19\u0e25\u0e30 80 \u0e1a\u0e32\u0e17 \u0e41\u0e1c\u0e07\u0e25\u0e30 80 \u0e1a\u0e32\u0e17 \u0e02\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e25\u0e30 2,000 \u0e01\u0e27\u0e48\u0e32\u0e1a\u0e32\u0e17<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u0e1c\u0e21\u0e02\u0e22\u0e32\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e23\u0e01 \u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e08\u0e19\u0e41\u0e01\u0e48 \u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33 \u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e08\u0e30\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e1a\u0e33\u0e19\u0e32\u0e0d\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49 \u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e44\u0e2b\u0e19\u0e40\u0e23\u0e32\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e0a\u0e2d\u0e1a\u0e01\u0e34\u0e19\u0e01\u0e25\u0e49\u0e27\u0e22\u0e40\u0e23\u0e32\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e01\u0e25\u0e49\u0e27\u0e22 \u0e40\u0e23\u0e32\u0e0a\u0e2d\u0e1a\u0e01\u0e34\u0e19\u0e25\u0e30\u0e21\u0e38\u0e14 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e25\u0e30\u0e21\u0e38\u0e14 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e1e\u0e37\u0e0a\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27 \u0e15\u0e49\u0e2d\u0e07\u0e04\u0e25\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e32\u0e01\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e15\u0e48\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e23\u0e07 \u0e2d\u0e48\u0e32\u0e19\u0e2a\u0e30\u0e2a\u0e21\u0e21\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e2a\u0e30\u0e2a\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e08\u0e23\u0e34\u0e07\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e22\u0e39\u0e17\u0e39\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e22\u0e39\u0e17\u0e39\u0e1a\u0e40\u0e02\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e25\u0e49\u0e27 \u0e21\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e08\u0e30\u0e23\u0e39\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e32 4-5 \u0e1b\u0e35 \u0e41\u0e15\u0e48\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e1e\u0e2d\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e47\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e25\u0e30\u0e40\u0e25\u0e48\u0e21\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e25\u0e2d\u0e07\u0e17\u0e33\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e25\u0e2d\u0e07\u0e1c\u0e34\u0e14\u0e25\u0e2d\u0e07\u0e16\u0e39\u0e01 \u0e15\u0e37\u0e48\u0e19\u0e15\u0e35 5 \u0e1c\u0e2a\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e01\u0e48 6 \u0e42\u0e21\u0e07\u0e40\u0e0a\u0e49\u0e32\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e01\u0e48\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e40\u0e14\u0e34\u0e19\u0e14\u0e39\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35 \u0e01\u0e25\u0e49\u0e27\u0e22 \u0e25\u0e30\u0e21\u0e38\u0e14 \u0e1d\u0e23\u0e31\u0e48\u0e07 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e25\u0e2d\u0e07\u0e01\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e22\u0e37\u0e19\u0e15\u0e49\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 7-8 \u0e42\u0e21\u0e07\u0e40\u0e0a\u0e49\u0e32 \u0e01\u0e34\u0e19\u0e02\u0e49\u0e32\u0e27\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e16\u0e36\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e07\u0e01\u0e47\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e2b\u0e0d\u0e49\u0e32\u0e40\u0e19\u0e40\u0e1b\u0e35\u0e22\u0e23\u0e4c \u0e41\u0e2b\u0e19\u0e41\u0e14\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e40\u0e2d\u0e07 \u0e44\u0e1b\u0e40\u0e2d\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e32 2 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e48\u0e07\u0e08\u0e32\u0e01\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e20\u0e39\u0e40\u0e27\u0e35\u0e22\u0e07 \u0e21\u0e32 4 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e23\u0e32\u0e04\u0e32\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21\u0e25\u0e30 70-80 \u0e1a\u0e32\u0e17 \u0e1a\u0e27\u0e01\u0e04\u0e48\u0e32\u0e2a\u0e48\u0e07 25 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e1a\u0e32\u0e07\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e01\u0e47\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized wp-image-245632 size-large\"><img decoding=\"async\" width=\"914\" height=\"1024\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2023\/03\/5-9-914x1024.png\" alt=\"\" class=\"wp-image-245632\" style=\"width:1049px;height:auto\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/5-9-914x1024.png 914w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/5-9-268x300.png 268w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/5-9-768x861.png 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/5-9-696x780.png 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/5-9-1068x1197.png 1068w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/5-9-375x420.png 375w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/5-9.png 1108w\" sizes=\"(max-width: 914px) 100vw, 914px\" \/><figcaption class=\"wp-element-caption\">\u0e41\u0e2b\u0e19\u0e41\u0e14\u0e07 \u0e21\u0e35\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e40\u0e22\u0e2d\u0e30\u0e01\u0e27\u0e48\u0e32 30 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u0e1c\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e1b\u0e25\u0e32 \u0e19\u0e32\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e02\u0e22\u0e14\u0e39\u0e41\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e19\u0e32\u0e01\u0e47\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e22\u0e39\u0e48 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e15\u0e49\u0e19\u0e22\u0e32\u0e07 \u0e15\u0e30\u0e40\u0e04\u0e35\u0e22\u0e19\u0e17\u0e2d\u0e07 \u0e2a\u0e31\u0e01\u0e17\u0e2d\u0e07 \u0e1e\u0e30\u0e22\u0e39\u0e07 \u0e08\u0e33\u0e19\u0e27\u0e19 556 \u0e15\u0e49\u0e19 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e44\u0e23\u0e48 (\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e02\u0e32\u0e22) \u0e1b\u0e25\u0e39\u0e01\u0e21\u0e32 15-16 \u0e1b\u0e35\u0e41\u0e25\u0e49\u0e27\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2a\u0e27\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e47\u0e08\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e2b\u0e0d\u0e49\u0e32\u0e40\u0e19\u0e40\u0e1b\u0e35\u0e22\u0e23\u0e4c \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1d\u0e23\u0e31\u0e48\u0e07 \u0e1b\u0e25\u0e39\u0e01\u0e01\u0e25\u0e49\u0e27\u0e22\u0e01\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e01\u0e25\u0e49\u0e27\u0e22\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e14\u0e39\u0e41\u0e25\u0e44\u0e21\u0e49\u0e43\u0e2b\u0e0d\u0e48 \u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25 \u0e21\u0e30\u0e22\u0e07\u0e0a\u0e34\u0e14 \u0e40\u0e07\u0e32\u0e30 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49\u0e15\u0e31\u0e14\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e35 \u0e1b\u0e25\u0e39\u0e01\u0e21\u0e32 15-16 \u0e1b\u0e35 \u0e41\u0e21\u0e48\u0e44\u0e1b\u0e02\u0e32\u0e22\u0e15\u0e32\u0e21\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18 \u0e41\u0e21\u0e48\u0e2a\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e02\u0e32\u0e22 (\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e2d\u0e19\u0e42\u0e21\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e27\u0e31\u0e19\u0e40\u0e2a\u0e32\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e37\u0e2d\u0e22 \u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e07)\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e1b \u0e01\u0e25\u0e49\u0e27\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e07\u0e32\u0e21 \u0e01\u0e25\u0e49\u0e27\u0e22\u0e40\u0e17\u0e48\u0e32\u0e04\u0e19 9 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e49\u0e07\u0e17\u0e49\u0e2d\u0e07 \u0e44\u0e21\u0e49\u0e1c\u0e25\u0e40\u0e2d\u0e32\u0e25\u0e07 4-5 \u0e15\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e16\u0e49\u0e32\u0e25\u0e07\u0e40\u0e22\u0e2d\u0e30\u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21 \u0e25\u0e07 5 \u0e15\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e27\u0e34\u0e18\u0e35\u0e41\u0e01\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized wp-image-245628 size-large\"><img decoding=\"async\" width=\"1000\" height=\"1024\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2023\/03\/1-8-1000x1024.png\" alt=\"\" class=\"wp-image-245628\" style=\"width:1049px;height:auto\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/1-8-1000x1024.png 1000w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/1-8-293x300.png 293w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/1-8-768x787.png 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/1-8-696x713.png 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/1-8-1068x1094.png 1068w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/1-8-410x420.png 410w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/1-8.png 1108w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e19\u0e32\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e27\u0e48\u0e32 30 \u0e1b\u0e35 \u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e1b\u0e25\u0e39\u0e01\u0e44\u0e27\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e15\u0e49\u0e19<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07 20 \u0e1b\u0e35 \u0e08\u0e36\u0e07\u0e08\u0e30\u0e02\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2a\u0e19\u0e43\u0e08 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e47\u0e19\u0e33\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e21\u0e32\u0e1b\u0e25\u0e39\u0e01 \u0e25\u0e07\u0e17\u0e38\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e21\u0e32\u0e1b\u0e25\u0e39\u0e01 \u0e15\u0e49\u0e19\u0e25\u0e30 250 \u0e1a\u0e32\u0e17 \u0e40\u0e23\u0e32\u0e08\u0e30\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e25\u0e39\u0e01\u0e40\u0e2d\u0e35\u0e22\u0e07 45 \u0e2d\u0e07\u0e28\u0e32 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e34\u0e14\u0e08\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e01\u0e47\u0e1b\u0e25\u0e39\u0e01\u0e40\u0e25\u0e22\u0e21\u0e31\u0e19\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e02\u0e2d\u0e07\u0e21\u0e31\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a\u0e01\u0e34\u0e19\u0e08\u0e19\u0e41\u0e2b\u0e27\u0e48\u0e07 \u0e01\u0e47\u0e17\u0e33\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e31\u0e01\u0e44\u0e25\u0e48\u0e41\u0e21\u0e25\u0e07 \u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e41\u0e21\u0e25\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e39\u0e48 (\u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e01\u0e32\u0e27\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e01\u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01) \u0e09\u0e35\u0e14\u0e22\u0e32\u0e1e\u0e48\u0e19\u0e41\u0e21\u0e25\u0e07\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e40\u0e2a\u0e35\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e01\u0e47\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e48\u0e32 \u0e1f\u0e31\u0e01\u0e17\u0e2d\u0e07 \u0e1e\u0e37\u0e0a\u0e25\u0e49\u0e21\u0e25\u0e38\u0e01 \u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19 \u0e2d\u0e22\u0e32\u0e01\u0e01\u0e34\u0e19\u0e2d\u0e30\u0e44\u0e23 \u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e01\u0e47\u0e1b\u0e25\u0e39\u0e01 \u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e19\u0e32\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2d\u0e22\u0e39\u0e48 \u0e21.3 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 30 \u0e01\u0e27\u0e48\u0e32\u0e1b\u0e35 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e01\u0e48\u0e2d\u0e19 \u0e15\u0e30\u0e40\u0e04\u0e35\u0e22\u0e19 \u0e2a\u0e31\u0e01\u0e17\u0e2d\u0e07 \u0e1e\u0e30\u0e22\u0e39\u0e07 \u0e1b\u0e25\u0e39\u0e01 15-16 \u0e1b\u0e35<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07<br><\/strong><strong>\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a <\/strong><strong>30 : 30 : 30 : 10<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27 30 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c 30 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e17\u0e33\u0e2a\u0e27\u0e19 30 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 10 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e42\u0e04\u0e01 \u0e2b\u0e19\u0e2d\u0e07 \u0e19\u0e32 \u0e17\u0e35\u0e48\u0e04\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e33\u0e43\u0e19\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e42\u0e04\u0e01 \u0e2b\u0e19\u0e2d\u0e07 \u0e19\u0e32 \u0e2b\u0e25\u0e31\u0e01\u0e46 \u0e08\u0e30\u0e21\u0e35\u0e04\u0e25\u0e2d\u0e07\u0e44\u0e2a\u0e49\u0e44\u0e01\u0e48 \u0e04\u0e25\u0e2d\u0e07\u0e25\u0e49\u0e2d\u0e21\u0e19\u0e32\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e34\u0e49\u0e07\u0e17\u0e49\u0e32\u0e22\u0e27\u0e48\u0e32 \u0e40\u0e23\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e01\u0e34\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e43\u0e2b\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e1b\u0e25\u0e39\u0e01\u0e21\u0e30\u0e19\u0e32\u0e27 \u0e1b\u0e25\u0e39\u0e01\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e04\u0e23\u0e31\u0e27\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e04\u0e48\u0e2d\u0e22\u0e41\u0e08\u0e01\u0e08\u0e48\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e14\u0e39\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e31\u0e49\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e08\u0e30\u0e23\u0e48\u0e2d\u0e22\u0e2b\u0e23\u0e2d \u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e01\u0e31\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized wp-image-245638 size-large\"><img decoding=\"async\" width=\"1024\" height=\"948\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2023\/03\/12-4-1024x948.png\" alt=\"\" class=\"wp-image-245638\" style=\"width:1049px;height:auto\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/12-4-1024x948.png 1024w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/12-4-300x278.png 300w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/12-4-768x711.png 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/12-4-696x644.png 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/12-4-1068x989.png 1068w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/12-4-454x420.png 454w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2023\/03\/12-4.png 1108w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e44\u0e21\u0e49\u0e2d\u0e31\u0e19\u0e23\u0e48\u0e21\u0e23\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;&#8230;..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e212566<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e38\u0e19\u0e40\u0e14\u0e34\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e08\u0e36\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32 \u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e0a\u0e19\u0e1a\u0e17\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e22\u0e40\u0e22\u0e32\u0e27\u0e4c&nbsp;&nbsp; \u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e40\u0e02\u0e15\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27 \u0e2b\u0e23\u0e37\u0e2d \u0e1e\u0e35\u0e48\u0e19\u0e34\u0e14 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 187 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e1a\u0e49\u0e32\u0e19\u0e01\u0e07\u0e01\u0e25\u0e32\u0e07 \u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e19\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c 081-934-9411 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e35\u0e48\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e44\u0e14\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e41\u0e25\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e21\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e22\u0e2d\u0e22\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e21\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e35 2545-2546 \u0e04\u0e38\u0e13\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e44\u0e14\u0e49\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e36\u0e48\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e44\u0e21\u0e48\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e47\u0e08\u0e30\u0e23\u0e48\u0e2d\u0e22\u0e2b\u0e23\u0e2d\u0e41\u0e25\u0e30\u0e2b\u0e21\u0e14\u0e44\u0e1b\u0e44\u0e23\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1b\u0e38\u0e4b\u0e22\u0e2b\u0e21\u0e31\u0e01\u0e17\u0e35\u0e48\u0e1e\u0e35\u0e48\u0e19\u0e34\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e22\u0e32\u0e06\u0e48\u0e32\u0e41\u0e21\u0e25\u0e07\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e27\u0e34\u0e18\u0e35\u0e17\u0e33\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e31\u0e01\u0e44\u0e25\u0e48\u0e41\u0e21\u0e25\u0e07\u0e28<\/p>\n","protected":false},"author":3,"featured_media":245640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,45758],"tags":[40351,18],"msn":[],"line":[],"class_list":["post-245627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-plants-vegetables-fruit","category-techno","tag-40351","tag-18"],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/245627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/comments?post=245627"}],"version-history":[{"count":3,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/245627\/revisions"}],"predecessor-version":[{"id":313848,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/245627\/revisions\/313848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media\/245640"}],"wp:attachment":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media?parent=245627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/categories?post=245627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags?post=245627"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/msn?post=245627"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/line?post=245627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}