{"id":291957,"date":"2024-10-13T20:24:40","date_gmt":"2024-10-13T13:24:40","guid":{"rendered":"https:\/\/www.technologychaoban.com\/?p=291957"},"modified":"2024-10-13T20:24:40","modified_gmt":"2024-10-13T13:24:40","slug":"%e0%b8%aa-%e0%b8%9b-%e0%b8%81-%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b8%a7%e0%b8%b2%e0%b8%87%e0%b8%9e%e0%b8%a7%e0%b8%87%e0%b8%a1%e0%b8%b2%e0%b8%a5%e0%b8%b2-%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a1","status":"publish","type":"post","link":"https:\/\/www.khaosod.co.th\/technologychaoban\/techno-news\/article_291957","title":{"rendered":"\u0e2a.\u0e1b.\u0e01. \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32 \u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 &#8220;\u0e27\u0e31\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a&#8221; \u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57 \u0e13 \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e40\u0e02\u0e15\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23"},"content":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e56.\u0e53\u0e50 \u0e19. \u0e19\u0e32\u0e22\u0e27\u0e34\u0e13\u0e30\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e2a\u0e38\u0e02 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e35\u0e0a\u0e32 \u0e25\u0e34\u0e49\u0e21\u0e16\u0e27\u0e34\u0e25 \u0e23\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e21\u0e23\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e41\u0e02\u0e27\u0e07\u0e42\u0e2a\u0e20\u0e32 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e25\u0e32\u0e07 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e30 \u0e25\u0e34\u0e20\u0e15\u0e30\u0e44\u0e0a\u0e22\u0e42\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57<br \/>\n\u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u0e40\u0e02\u0e15\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-291958\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/2793AB47-528C-483F-850B-503A2B67169B.jpeg\" alt=\"\" width=\"600\" height=\"308\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/2793AB47-528C-483F-850B-503A2B67169B.jpeg 600w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/2793AB47-528C-483F-850B-503A2B67169B-300x154.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>\u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 &#8220;\u0e27\u0e31\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a&#8221; \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e58 \u0e02\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e43\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e17\u0e35\u0e48\u0e17\u0e23\u0e07\u0e21\u0e35\u0e15\u0e48\u0e2d\u0e1b\u0e27\u0e07\u0e0a\u0e19\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e49\u0e19\u0e1e\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e21\u0e34\u0e44\u0e14\u0e49 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e01\u0e23\u0e38\u0e13\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e01\u0e23\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e44\u0e14\u0e49\u0e02\u0e2d\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e44\u0e14\u0e49\u0e21\u0e35\u0e21\u0e15\u0e34\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e52\u0e56 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e56 \u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e27\u0e48\u0e32 &#8220;\u0e27\u0e31\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a&#8221; \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e29\u0e31\u0e15\u0e23\u0e34\u0e22\u0e4c\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1c\u0e39\u0e49\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 (\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 )\u0e43\u0e19\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e21\u0e35\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 \u0e52\u0e57\u0e59 \u0e44\u0e23\u0e48 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34 \u0e43\u0e19 \u0e59<br \/>\n\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49 \u0e02\u0e2d\u0e07 \u201c\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59\u201d \u0e2a\u0e27\u0e19\u0e2a\u0e27\u0e22\u0e01\u0e25\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e43\u0e15\u0e49\u0e23\u0e48\u0e21\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e23\u0e21\u0e35\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e04\u0e37\u0e2d<\/p>\n<p>\u0e51. \u0e08\u0e32\u0e01\u0e2d\u0e14\u0e35\u0e15\u0e2a\u0e19\u0e32\u0e21\u0e21\u0e49\u0e32\u0e2a\u0e39\u0e48 \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e14\u0e35\u0e15 \u201c\u0e2a\u0e19\u0e32\u0e21\u0e21\u0e49\u0e32\u0e19\u0e32\u0e07\u0e40\u0e25\u0e34\u0e49\u0e07\u201d \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e1b\u0e23\u0e21\u0e32\u0e20\u0e34\u0e44\u0e18\u0e22\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e38\u0e02\u0e41\u0e01\u0e48\u0e1b\u0e27\u0e07\u0e0a\u0e19<img decoding=\"async\" class=\"alignnone size-full wp-image-291960\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/22C371F7-64F7-484A-84BE-5AC04F7BC683.jpeg\" alt=\"\" width=\"1015\" height=\"839\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/22C371F7-64F7-484A-84BE-5AC04F7BC683.jpeg 1015w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/22C371F7-64F7-484A-84BE-5AC04F7BC683-300x248.jpeg 300w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/22C371F7-64F7-484A-84BE-5AC04F7BC683-768x635.jpeg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/22C371F7-64F7-484A-84BE-5AC04F7BC683-696x575.jpeg 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/22C371F7-64F7-484A-84BE-5AC04F7BC683-508x420.jpeg 508w\" sizes=\"(max-width: 1015px) 100vw, 1015px\" \/><img decoding=\"async\" class=\"alignnone size-full wp-image-291959\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/56F4C380-B4DB-43E3-BED5-3891CBBE983D.jpeg\" alt=\"\" width=\"1016\" height=\"901\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/56F4C380-B4DB-43E3-BED5-3891CBBE983D.jpeg 1016w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/56F4C380-B4DB-43E3-BED5-3891CBBE983D-300x266.jpeg 300w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/56F4C380-B4DB-43E3-BED5-3891CBBE983D-768x681.jpeg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/56F4C380-B4DB-43E3-BED5-3891CBBE983D-696x617.jpeg 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/56F4C380-B4DB-43E3-BED5-3891CBBE983D-474x420.jpeg 474w\" sizes=\"(max-width: 1016px) 100vw, 1016px\" \/><\/p>\n<p>\u0e52. \u0e2a\u0e27\u0e19\u0e2a\u0e27\u0e22\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e43\u0e08\u0e01\u0e25\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f : \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e52\u0e57\u0e59 \u0e44\u0e23\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e35\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e19\u0e40\u0e02\u0e15\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e01\u0e34\u0e15\u0e15\u0e34<\/p>\n<p>\u0e2a\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e1e.\u0e28.\u0e52\u0e55\u0e56\u0e51 \u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1e.\u0e28. \u0e52\u0e55\u0e56\u0e57<\/p>\n<p>\u0e53. \u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e1b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33 : \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1b\u0e13\u0e34\u0e18\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e23\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e2b\u0e24\u0e17\u0e31\u0e22\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e02\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e1b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u201d \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e33\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49<img decoding=\"async\" class=\"alignnone size-large wp-image-291963\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/162D49EF-F89C-4C88-9CE5-73AE3E9C3732-683x1024.jpeg\" alt=\"\" width=\"683\" height=\"1024\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/162D49EF-F89C-4C88-9CE5-73AE3E9C3732-683x1024.jpeg 683w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/162D49EF-F89C-4C88-9CE5-73AE3E9C3732-200x300.jpeg 200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/162D49EF-F89C-4C88-9CE5-73AE3E9C3732-768x1152.jpeg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/162D49EF-F89C-4C88-9CE5-73AE3E9C3732-1024x1536.jpeg 1024w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/162D49EF-F89C-4C88-9CE5-73AE3E9C3732-696x1044.jpeg 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/162D49EF-F89C-4C88-9CE5-73AE3E9C3732-280x420.jpeg 280w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/162D49EF-F89C-4C88-9CE5-73AE3E9C3732.jpeg 1045w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><img decoding=\"async\" class=\"alignnone size-large wp-image-291961\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/C49DE8C0-076E-44D2-A43D-4DDA3FECF27E-707x1024.jpeg\" alt=\"\" width=\"707\" height=\"1024\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/C49DE8C0-076E-44D2-A43D-4DDA3FECF27E-707x1024.jpeg 707w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/C49DE8C0-076E-44D2-A43D-4DDA3FECF27E-207x300.jpeg 207w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/C49DE8C0-076E-44D2-A43D-4DDA3FECF27E-768x1113.jpeg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/C49DE8C0-076E-44D2-A43D-4DDA3FECF27E-696x1008.jpeg 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/C49DE8C0-076E-44D2-A43D-4DDA3FECF27E-290x420.jpeg 290w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/C49DE8C0-076E-44D2-A43D-4DDA3FECF27E.jpeg 965w\" sizes=\"(max-width: 707px) 100vw, 707px\" \/><\/p>\n<p>\u0e54. \u0e2a\u0e27\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 : \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e2a\u0e27\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e23\u0e37\u0e2d \u201cModern Park\u201d \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e21\u0e35\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e2a\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e27\u0e34\u0e16\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e27\u0e49\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07<\/p>\n<p>\u0e55. \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e1e\u0e48\u0e2d : \u0e14\u0e49\u0e27\u0e22\u0e2a\u0e33\u0e19\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e08\u0e36\u0e07\u0e21\u0e35\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e43\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e42\u0e14\u0e22\u0e19\u0e33<br \/>\n&#8211; \u201c\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59\u201d \u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e27\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49<br \/>\n&#8211; \u201c\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02 \u0e59\u201d \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e19\u0e33\u0e2a\u0e39\u0e48 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59<br \/>\n&#8211; \u201c\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2b\u0e22\u0e14\u0e19\u0e49\u0e33\u0e1e\u0e23\u0e30\u0e17\u0e31\u0e22\u201d \u0e17\u0e35\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07 \u0e19\u0e49\u0e33\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e2b\u0e24\u0e17\u0e31\u0e22\u0e14\u0e31\u0e48\u0e07\u0e2a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 \u0e57\u0e50 \u0e1b\u0e35 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e22\u0e32\u0e21\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e40\u0e07\u0e32\u0e08\u0e32\u0e01\u0e41\u0e1c\u0e48\u0e19\u0e19\u0e49\u0e33<br \/>\n&#8211; \u201c\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e44\u0e21\u0e49\u0e40\u0e08\u0e32\u0e30\u0e1a\u0e32\u0e01\u0e07\u201d \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e44\u0e21\u0e49\u0e40\u0e08\u0e32\u0e30\u0e1a\u0e32\u0e01\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e40\u0e04\u0e22\u0e40\u0e2a\u0e14\u0e47\u0e08\u0e44\u0e1b\u0e17\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e21\u0e35\u0e17\u0e48\u0e32\u0e19\u0e49\u0e33 \u0e19\u0e49\u0e33\u0e15\u0e01\u0e41\u0e25\u0e30\u0e25\u0e33\u0e18\u0e32\u0e23\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e1b\u0e48\u0e32\u0e1d\u0e19\u0e40\u0e02\u0e15\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21<img decoding=\"async\" class=\"alignnone size-full wp-image-291962\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/422A35AD-0407-4685-88AB-3AAD506524FC.jpeg\" alt=\"\" width=\"1015\" height=\"780\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/422A35AD-0407-4685-88AB-3AAD506524FC.jpeg 1015w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/422A35AD-0407-4685-88AB-3AAD506524FC-300x231.jpeg 300w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/422A35AD-0407-4685-88AB-3AAD506524FC-768x590.jpeg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/422A35AD-0407-4685-88AB-3AAD506524FC-80x60.jpeg 80w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/422A35AD-0407-4685-88AB-3AAD506524FC-696x535.jpeg 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/422A35AD-0407-4685-88AB-3AAD506524FC-547x420.jpeg 547w\" sizes=\"(max-width: 1015px) 100vw, 1015px\" \/><img decoding=\"async\" class=\"alignnone size-large wp-image-291964\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/9F0E85E1-5781-42A1-9B94-AC39C37354AE-683x1024.jpeg\" alt=\"\" width=\"683\" height=\"1024\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/9F0E85E1-5781-42A1-9B94-AC39C37354AE-683x1024.jpeg 683w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/9F0E85E1-5781-42A1-9B94-AC39C37354AE-200x300.jpeg 200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/9F0E85E1-5781-42A1-9B94-AC39C37354AE-768x1152.jpeg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/9F0E85E1-5781-42A1-9B94-AC39C37354AE-1024x1536.jpeg 1024w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/9F0E85E1-5781-42A1-9B94-AC39C37354AE-696x1044.jpeg 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/9F0E85E1-5781-42A1-9B94-AC39C37354AE-280x420.jpeg 280w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/9F0E85E1-5781-42A1-9B94-AC39C37354AE.jpeg 1045w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><br \/>\n\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e21\u0e35 \u201c\u0e2a\u0e23\u0e30\u0e19\u0e49\u0e33\u0e23\u0e39\u0e1b\u0e40\u0e25\u0e02 \u0e59\u201d \u0e41\u0e25\u0e30 \u201c\u0e2a\u0e27\u0e19\u0e1b\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u201d \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e14\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2f\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49<\/p>\n<p>\u0e56. \u0e41\u0e01\u0e49\u0e21\u0e25\u0e34\u0e07\u0e41\u0e2a\u0e19\u0e2a\u0e27\u0e22 : \u0e2a\u0e23\u0e30\u0e19\u0e49\u0e33\u0e23\u0e39\u0e1b\u0e40\u0e25\u0e02 \u0e59 \u0e44\u0e17\u0e22 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2f\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33 \u0e2b\u0e23\u0e37\u0e2d \u201c\u0e41\u0e01\u0e49\u0e21\u0e25\u0e34\u0e07\u201d \u0e43\u0e19\u0e22\u0e32\u0e21\u0e27\u0e34\u0e01\u0e24\u0e15\u0e08\u0e32\u0e01\u0e2d\u0e38\u0e17\u0e01\u0e20\u0e31\u0e22\u0e2d\u0e35\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1c\u0e31\u0e19\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e1b\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2f \u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49<\/p>\n<p>\u0e57. \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e49\u0e33 : \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e22\u0e31\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e01\u0e25\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33 \u0e1b\u0e25\u0e39\u0e01\u0e1e\u0e37\u0e0a\u0e0a\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33 \u0e1e\u0e37\u0e0a\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e1e\u0e37\u0e0a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33 \u0e21\u0e35\u0e1a\u0e48\u0e2d\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e1b\u0e25\u0e32\u0e19\u0e34\u0e25 \u0e1d\u0e32\u0e22\u0e0a\u0e30\u0e25\u0e2d\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e19\u0e49\u0e33\u0e0a\u0e31\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<img decoding=\"async\" class=\"alignnone size-large wp-image-291965\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/088FA8BD-0E6E-47D8-9DA5-3BE11467E396-683x1024.jpeg\" alt=\"\" width=\"683\" height=\"1024\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/088FA8BD-0E6E-47D8-9DA5-3BE11467E396-683x1024.jpeg 683w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/088FA8BD-0E6E-47D8-9DA5-3BE11467E396-200x300.jpeg 200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/088FA8BD-0E6E-47D8-9DA5-3BE11467E396-768x1152.jpeg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/088FA8BD-0E6E-47D8-9DA5-3BE11467E396-1024x1536.jpeg 1024w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/088FA8BD-0E6E-47D8-9DA5-3BE11467E396-696x1044.jpeg 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/088FA8BD-0E6E-47D8-9DA5-3BE11467E396-280x420.jpeg 280w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/088FA8BD-0E6E-47D8-9DA5-3BE11467E396.jpeg 1045w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><img decoding=\"async\" class=\"alignnone size-full wp-image-291966\" src=\"https:\/\/www.technologychaoban.com\/wp-content\/uploads\/2024\/10\/E4782707-4D93-486B-9CC3-CAFE35C1C930.jpeg\" alt=\"\" width=\"1015\" height=\"860\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/E4782707-4D93-486B-9CC3-CAFE35C1C930.jpeg 1015w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/E4782707-4D93-486B-9CC3-CAFE35C1C930-300x254.jpeg 300w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/E4782707-4D93-486B-9CC3-CAFE35C1C930-768x651.jpeg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/E4782707-4D93-486B-9CC3-CAFE35C1C930-696x590.jpeg 696w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2024\/10\/E4782707-4D93-486B-9CC3-CAFE35C1C930-496x420.jpeg 496w\" sizes=\"(max-width: 1015px) 100vw, 1015px\" \/><\/p>\n<p>\u0e58. \u0e2a\u0e27\u0e19\u0e1b\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 : \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e02\u0e2d\u0e07\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e42\u0e14\u0e22\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2f \u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e43\u0e2b\u0e49\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e23\u0e48\u0e21\u0e23\u0e37\u0e48\u0e19\u0e16\u0e36\u0e07\u0e23\u0e32\u0e27 \u0e54,\u0e55\u0e50\u0e50 \u0e15\u0e49\u0e19 \u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e27\u0e19\u0e1b\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e2d\u0e32\u0e17\u0e34 \u0e1b\u0e25\u0e39\u0e01\u0e1b\u0e48\u0e32 \u0e53 \u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e54 \u0e2d\u0e22\u0e48\u0e32\u0e07, \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e42\u0e15\u0e40\u0e23\u0e47\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e48\u0e21\u0e40\u0e07\u0e32 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e44\u0e21\u0e49\u0e2b\u0e32\u0e22\u0e32\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e24\u0e29\u0e35\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e2a\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e21\u0e34\u0e15\u0e34 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49<\/p>\n<p>\u0e59. \u0e2a\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 : \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e41\u0e2a\u0e19\u0e2a\u0e27\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e1b\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e15\u0e49\u0e23\u0e48\u0e21\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e23\u0e21\u0e35 \u201c\u0e1e\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u201d \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e2d\u0e31\u0e19\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e21\u0e34\u0e44\u0e14\u0e49<\/p>\n<p>\u0e02\u0e48\u0e32\u0e27\/\u0e20\u0e32\u0e1e : \u0e2a\u0e38\u0e23\u0e34\u0e22\u0e30 \u0e25\u0e34\u0e20\u0e15\u0e30\u0e44\u0e0a\u0e22\u0e42\u0e22 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e25\u0e32\u0e07 \u0e2a.\u0e1b.\u0e01.<br \/>\n\u0e17\u0e35\u0e48\u0e21\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 :<br \/>\n\u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13<br \/>\n\u0e19\u0e2a\u0e1e.\u0e44\u0e17\u0e22\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e56.\u0e53\u0e50 \u0e19. \u0e19\u0e32\u0e22\u0e27\u0e34\u0e13\u0e30\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e2a\u0e38\u0e02 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e35\u0e0a\u0e32 \u0e25\u0e34\u0e49\u0e21\u0e16\u0e27\u0e34\u0e25 \u0e23\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e21\u0e23\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e41\u0e02\u0e27\u0e07\u0e42\u0e2a\u0e20\u0e32 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e25\u0e32\u0e07 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e30 \u0e25\u0e34\u0e20\u0e15\u0e30\u0e44\u0e0a\u0e22\u0e42\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57 \u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u0e40\u0e02\u0e15\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 &#8220;\u0e27\u0e31\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a&#8221; \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e58 \u0e02\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e43\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 \u0e59 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e17\u0e35\u0e48\u0e17\u0e23\u0e07\u0e21\u0e35\u0e15\u0e48\u0e2d\u0e1b\u0e27\u0e07\u0e0a\u0e19\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e49\u0e19\u0e1e\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e21\u0e34\u0e44\u0e14\u0e49 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e01\u0e23\u0e38\u0e13\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e01\u0e23\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e44\u0e14\u0e49\u0e02\u0e2d\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e44\u0e14\u0e49\u0e21\u0e35\u0e21\u0e15\u0e34\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e52\u0e56 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e52\u0e55\u0e56\u0e56 \u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e27<\/p>\n","protected":false},"author":6,"featured_media":291967,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[6311,6182],"msn":[],"line":[],"class_list":["post-291957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-techno-news","tag-6311","tag-6182"],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/291957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/comments?post=291957"}],"version-history":[{"count":2,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/291957\/revisions"}],"predecessor-version":[{"id":291969,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/291957\/revisions\/291969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media\/291967"}],"wp:attachment":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media?parent=291957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/categories?post=291957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags?post=291957"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/msn?post=291957"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/line?post=291957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}