{"id":326208,"date":"2025-12-24T14:35:21","date_gmt":"2025-12-24T07:35:21","guid":{"rendered":"https:\/\/www.khaosod.co.th\/technologychaoban\/?p=326208"},"modified":"2025-12-24T14:35:26","modified_gmt":"2025-12-24T07:35:26","slug":"%e0%b8%97%e0%b8%8a-%e0%b8%aa%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b8%9b%e0%b8%b2%e0%b8%81%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b8%99%e0%b9%89%e0%b8%b3-4-%e0%b9%81%e0%b8%ab%e0%b9%88%e0%b8%87-%e0%b9%84","status":"publish","type":"post","link":"https:\/\/www.khaosod.co.th\/technologychaoban\/techno-news\/article_326208","title":{"rendered":"\u0e17\u0e0a. \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e1b\u0e32\u0e01\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33 4 \u0e41\u0e2b\u0e48\u0e07 \u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e2d\u0e48\u0e32\u0e27\u0e44\u0e17\u0e22\u0e15\u0e2d\u0e19\u0e1a\u0e19 \u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25 \u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15-18 \u0e18.\u0e04. 68 \u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e1b\u0e32\u0e01\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e2a\u0e33\u0e04\u0e31\u0e0d 4 \u0e41\u0e2b\u0e48\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0e1b\u0e32\u0e01\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e1a\u0e32\u0e07\u0e1b\u0e30\u0e01\u0e07 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32<\/li>\n\n\n\n<li>\u0e1b\u0e32\u0e01\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23<\/li>\n\n\n\n<li>\u0e1b\u0e32\u0e01\u0e04\u0e25\u0e2d\u0e07\u0e02\u0e38\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e34\u0e19\u0e34\u0e08\u0e43\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23<\/li>\n\n\n\n<li>\u0e1b\u0e32\u0e01\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e17\u0e48\u0e32\u0e08\u0e35\u0e19 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23<\/li>\n<\/ol>\n\n\n\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e17\u0e31\u0e49\u0e07 4 \u0e08\u0e38\u0e14 \u0e41\u0e15\u0e48\u0e1e\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 21 \u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e0a\u0e19\u0e34\u0e14\u0e40\u0e14\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1b\u0e25\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e2d\u0e01\u0e2b\u0e32\u0e07\u0e1e\u0e31\u0e14 (Planiliza parsia) \u0e1b\u0e25\u0e32\u0e2a\u0e35\u0e01\u0e38\u0e19 (Alepes djedaba) \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e32\u0e01\u0e38\u0e40\u0e23\u0e32\u0e2b\u0e19\u0e27\u0e14\u0e2a\u0e35\u0e48\u0e40\u0e2a\u0e49\u0e19 (Eleutheronema etradactylum)<\/p>\n\n\n\n<p>\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c<\/p>\n\n\n\n<p>\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e2d\u0e48\u0e32\u0e27\u0e44\u0e17\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2b\u0e0d\u0e49\u0e32\u0e17\u0e30\u0e40\u0e25\u0e2d\u0e48\u0e32\u0e27\u0e04\u0e38\u0e49\u0e07\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e27 (\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e1a\u0e1f\u0e49\u0e32) \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16-19 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568 \u0e14\u0e49\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e2d\u0e27\u0e19\u0e25\u0e2d\u0e22\u0e15\u0e34\u0e14\u0e15\u0e32 \u0e02\u0e19\u0e32\u0e14\u0e15\u0e32 4 \u0e40\u0e0b\u0e19\u0e15\u0e34\u0e40\u0e21\u0e15\u0e23 \u0e22\u0e32\u0e27 100 \u0e40\u0e21\u0e15\u0e23<\/p>\n\n\n\n<p>\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e48\u0e32\u0e27\u0e04\u0e38\u0e49\u0e07\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e19 \u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2b\u0e32\u0e14\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e27 (\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e1a\u0e1f\u0e49\u0e32) \u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e15\u0e31\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e47\u0e01 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1b\u0e25\u0e32\u0e14\u0e2d\u0e01\u0e2b\u0e21\u0e32\u0e01 \u0e1b\u0e25\u0e32\u0e2a\u0e25\u0e34\u0e14\u0e17\u0e30\u0e40\u0e25\u0e08\u0e38\u0e14\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e2d\u0e01<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2025\/12\/890472-1200x900.jpg\" alt=\"\" class=\"wp-image-326210\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2025\/12\/890472-1200x900.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2025\/12\/890472-768x576.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2025\/12\/890472.jpg 1477w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e19\u0e49\u0e33\u0e17\u0e30\u0e40\u0e25\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e36\u0e01\u0e19\u0e49\u0e33 1.0-2.5 \u0e40\u0e21\u0e15\u0e23 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e47\u0e21 31 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e1e\u0e31\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e14-\u0e14\u0e48\u0e32\u0e07 8.18 \u0e2d\u0e2d\u0e01\u0e0b\u0e34\u0e40\u0e08\u0e19\u0e25\u0e30\u0e25\u0e32\u0e22\u0e19\u0e49\u0e33 7.92 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e01\u0e23\u0e31\u0e21\u0e15\u0e48\u0e2d\u0e25\u0e34\u0e15\u0e23 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 28.0 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a 1.0 \u0e40\u0e21\u0e15\u0e23<\/p>\n\n\n\n<p>\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2b\u0e32\u0e14\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e27 (\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e1a\u0e1f\u0e49\u0e32) \u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e15\u0e31\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e47\u0e01 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e15\u0e31\u0e27\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22 47.48 \u0e01\u0e23\u0e31\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e25\u0e33\u0e15\u0e31\u0e27\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22 13.70 \u0e40\u0e0b\u0e19\u0e15\u0e34\u0e40\u0e21\u0e15\u0e23 \u0e2a\u0e48\u0e27\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e19\u0e49\u0e33\u0e17\u0e30\u0e40\u0e25\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e36\u0e01\u0e19\u0e49\u0e33 0.5 \u0e40\u0e21\u0e15\u0e23 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e47\u0e21 31 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e1e\u0e31\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e14-\u0e14\u0e48\u0e32\u0e07 8.30 \u0e2d\u0e2d\u0e01\u0e0b\u0e34\u0e40\u0e08\u0e19\u0e25\u0e30\u0e25\u0e32\u0e22\u0e19\u0e49\u0e33 8.39 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e01\u0e23\u0e31\u0e21\u0e15\u0e48\u0e2d\u0e25\u0e34\u0e15\u0e23 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 28.0 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a 0.5 \u0e40\u0e21\u0e15\u0e23<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e2d\u0e48\u0e32\u0e27\u0e44\u0e17\u0e22\u0e15\u0e2d\u0e19\u0e1a\u0e19 \u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25 \u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15-18 \u0e18.\u0e04. 68 \u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e1b\u0e32\u0e01\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e2a\u0e33\u0e04\u0e31\u0e0d 4 \u0e41\u0e2b\u0e48\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e17\u0e31\u0e49\u0e07 4 \u0e08\u0e38\u0e14 \u0e41\u0e15\u0e48\u0e1e\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 21 \u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e0a\u0e19\u0e34\u0e14\u0e40\u0e14\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1b\u0e25\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e2d\u0e01\u0e2b\u0e32\u0e07\u0e1e\u0e31\u0e14 (Planiliza parsia) \u0e1b\u0e25\u0e32\u0e2a\u0e35\u0e01\u0e38\u0e19 (Alepes djedaba) \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e32\u0e01\u0e38\u0e40\u0e23\u0e32\u0e2b\u0e19\u0e27\u0e14\u0e2a\u0e35\u0e48\u0e40\u0e2a\u0e49\u0e19 (Eleutheronema etradactylum) \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e2d\u0e48\u0e32\u0e27\u0e44\u0e17\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2b\u0e0d\u0e49\u0e32\u0e17\u0e30\u0e40\u0e25\u0e2d\u0e48\u0e32\u0e27\u0e04\u0e38\u0e49\u0e07\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e27 (\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e1a\u0e1f\u0e49\u0e32) \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16-19 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568 \u0e14\u0e49\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e2d\u0e27\u0e19\u0e25\u0e2d\u0e22\u0e15\u0e34\u0e14\u0e15\u0e32 \u0e02\u0e19\u0e32\u0e14\u0e15\u0e32 4 \u0e40\u0e0b\u0e19\u0e15\u0e34\u0e40\u0e21\u0e15\u0e23 \u0e22\u0e32\u0e27 100 \u0e40\u0e21\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e48\u0e32\u0e27\u0e04\u0e38\u0e49\u0e07\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e19 \u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2b\u0e32\u0e14\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e27 (\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e1a\u0e1f\u0e49\u0e32) \u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e15\u0e31\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e47\u0e01 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e1e\u0e1a\u0e1b\u0e25\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1b\u0e25\u0e32\u0e14\u0e2d\u0e01\u0e2b\u0e21\u0e32\u0e01 \u0e1b\u0e25\u0e32\u0e2a\u0e25\u0e34\u0e14\u0e17\u0e30\u0e40\u0e25\u0e08\u0e38\u0e14\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e2d\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e19\u0e49\u0e33\u0e17\u0e30\u0e40\u0e25\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e36\u0e01\u0e19\u0e49\u0e33 1<\/p>\n","protected":false},"author":6,"featured_media":326211,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[4607],"msn":[],"line":[],"class_list":["post-326208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-techno-news","tag-4607"],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/326208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/comments?post=326208"}],"version-history":[{"count":1,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/326208\/revisions"}],"predecessor-version":[{"id":326212,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/326208\/revisions\/326212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media\/326211"}],"wp:attachment":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media?parent=326208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/categories?post=326208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags?post=326208"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/msn?post=326208"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/line?post=326208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}