{"id":344886,"date":"2026-08-30T14:17:34","date_gmt":"2026-08-30T07:17:34","guid":{"rendered":"https:\/\/www.khaosod.co.th\/technologychaoban\/?p=344886"},"modified":"2026-09-01T14:19:56","modified_gmt":"2026-09-01T07:19:56","slug":"%e0%b9%80%e0%b8%a1%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89","status":"publish","type":"post","link":"https:\/\/www.khaosod.co.th\/technologychaoban\/techno-news\/article_344886","title":{"rendered":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e41\u0e04\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e40\u0e1b\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e27\u0e34\u0e16\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22 \u0e0a\u0e27\u0e19\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e27\u0e34\u0e16\u0e35 \u201c\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e07\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e04\u0e23\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32 \u201c\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u201d \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e41\u0e04\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e1c\u0e31\u0e01 \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e14\u0e39\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e49\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e19\u0e35\u0e49 \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e22\u0e01\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e19\u0e1a\u0e17\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e21\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19 <strong>\u0e15\u0e25\u0e32\u0e14\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u201c\u0e2a\u0e35\u0e2a\u0e31\u0e19 \u0e25\u0e35\u0e25\u0e32 \u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e07\u201d \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5\u20136 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e40\u0e27\u0e25\u0e32 08.00\u201317.00 \u0e19. <\/strong>\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e16\u0e49\u0e32\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e15\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e23\u0e31\u0e01\u0e27\u0e34\u0e16\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23\u201d \u0e01\u0e47\u0e04\u0e07\u0e44\u0e21\u0e48\u0e1c\u0e34\u0e14\u0e19\u0e31\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e0a\u0e49\u0e2d\u0e1b\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e14\u0e35\u0e08\u0e32\u0e01\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e08\u0e23\u0e34\u0e07 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e32\u0e2d\u0e48\u0e32\u0e19\u0e08\u0e32\u0e01\u0e15\u0e33\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747280_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344895\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747280_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747280_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747280_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747280_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e1e\u0e31\u0e19\u0e08\u0e48\u0e32\u0e40\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 \u0e21\u0e32\u0e25\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f<\/strong> \u0e40\u0e1c\u0e22\u0e16\u0e36\u0e07\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e27\u0e48\u0e32 \u201c\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e19\u0e33\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e08\u0e23\u0e34\u0e07\u0e21\u0e32\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e1a\u0e1b\u0e30 \u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e1e\u0e39\u0e14\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e04\u0e37\u0e2d \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e0a\u0e27\u0e19\u0e21\u0e32 \u201c\u0e14\u0e39\u0e40\u0e01\u0e29\u0e15\u0e23\u201d \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e41\u0e15\u0e48\u0e0a\u0e27\u0e19\u0e21\u0e32 \u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e33\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e33\u0e08\u0e23\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e04\u0e19\u0e1b\u0e25\u0e39\u0e01\u0e08\u0e23\u0e34\u0e07 \u0e08\u0e32\u0e01 \u201c\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e19\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u201d \u0e2a\u0e39\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e21\u0e38\u0e21\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e04\u0e37\u0e2d \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u201c\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e23\u0e2a \u0e08\u0e32\u0e01\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u201d<\/strong> \u0e17\u0e35\u0e48\u0e2b\u0e22\u0e34\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49\u0e15\u0e31\u0e27 <strong>\u201c\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u201d<\/strong> \u0e21\u0e32\u0e40\u0e25\u0e48\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e32\u0e17\u0e34 \u0e1b\u0e25\u0e32\u0e41\u0e2b\u0e49\u0e07 \u0e01\u0e25\u0e49\u0e27\u0e22\u0e15\u0e32\u0e01 \u0e1c\u0e31\u0e01\u0e14\u0e2d\u0e07 \u0e1b\u0e25\u0e32\u0e23\u0e49\u0e32 \u0e41\u0e2b\u0e19\u0e21 \u0e01\u0e25\u0e49\u0e27\u0e22\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e01\u0e27\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e2b\u0e47\u0e19\u0e08\u0e19\u0e0a\u0e34\u0e19\u0e15\u0e32 \u0e08\u0e23\u0e34\u0e07\u0e46\u0e41\u0e25\u0e49\u0e27\u0e0b\u0e48\u0e2d\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e22\u0e35\u0e2a\u0e15\u0e4c \u0e23\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e04\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39 \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e2a\u0e34\u0e48\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d \u201c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e09\u0e1a\u0e31\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u201d \u0e17\u0e35\u0e48\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e34\u0e14\u0e04\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e14\u0e2d\u0e32\u0e22\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747282_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344892\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747282_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747282_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747282_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747282_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747283_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344893\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747283_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747283_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747283_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747283_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07 \u201c\u0e40\u0e01\u0e25\u0e37\u0e2d\u201d \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e14\u0e35\u0e41\u0e04\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e47\u0e21<\/strong> \u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e41\u0e27\u0e30\u0e04\u0e37\u0e2d\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 <strong>\u201c\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e25\u0e37\u0e2d\u201d<\/strong> \u0e17\u0e35\u0e48\u0e08\u0e30\u0e1e\u0e32\u0e44\u0e1b\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e40\u0e21\u0e47\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e46 \u0e1a\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e31\u0e2a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e2a\u0e32\u0e23\u0e44\u0e2d\u0e42\u0e2d\u0e14\u0e35\u0e19\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e02\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e23\u0e13\u0e35\u0e22\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e01\u0e19\u0e34\u0e29\u0e10\u0e32\u0e18\u0e34\u0e23\u0e32\u0e0a\u0e40\u0e08\u0e49\u0e32 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e2a\u0e38\u0e14\u0e32\u0e2f \u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e21\u0e32\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e17\u0e23\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e2a\u0e32\u0e23\u0e44\u0e2d\u0e42\u0e2d\u0e14\u0e35\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e48\u0e32\u0e07\u0e44\u0e01\u0e25<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0 \u00a0\u00a0\u00a0    \u0e0a\u0e27\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e17\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e17\u0e31\u0e49\u0e07 5 \u0e1c\u0e48\u0e32\u0e19 4 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e01\u0e25\u0e37\u0e2d\u0e04\u0e37\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e44\u0e2d\u0e42\u0e2d\u0e14\u0e35\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e40\u0e25\u0e47\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e42\u0e25\u0e01 \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e41\u0e25\u0e30 \u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e32\u0e01\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2b\u0e22\u0e34\u0e1a\u0e21\u0e37\u0e2d \u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747295_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344898\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747295_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747295_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747295_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747295_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747284_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344902\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747284_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747284_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747284_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747284_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23&#8230;\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e25\u0e22 \u0e1f\u0e23\u0e35\u0e01\u0e27\u0e48\u0e32 8 \u0e27\u0e34\u0e0a\u0e32<\/strong> \u0e2a\u0e32\u0e22\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e01\u0e47\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e27\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e14\u0e39\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e23\u0e2d\u0e1a\u0e19\u0e35\u0e49\u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 <strong>\u0e2d\u0e1a\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30 Workshop \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 8 \u0e27\u0e34\u0e0a\u0e32 <\/strong>\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e17\u0e34 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 IoT Smart Farm Hybrid \u0e42\u0e14\u0e22 \u0e2d.\u0e19\u0e34\u0e23\u0e31\u0e19\u0e14\u0e23\u0e4c \u0e2a\u0e21\u0e1e\u0e07\u0e29\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u201c\u0e23\u0e49\u0e2d\u0e07 \u0e40\u0e25\u0e48\u0e19 \u0e40\u0e15\u0e49\u0e19 \u0e1b\u0e25\u0e39\u0e01\u201d \u0e42\u0e14\u0e22 \u0e2d.\u0e1e\u0e23\u0e23\u0e13\u0e1e\u0e23\u0e2b\u0e21\u0e1e\u0e23 \u0e40\u0e2d\u0e35\u0e48\u0e22\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32 \u0e08\u0e32\u0e01\u0e2a\u0e27\u0e19\u0e1e\u0e23\u0e23\u0e13\u0e1b\u0e31\u0e19\u0e2a\u0e38\u0e02 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e1c\u0e31\u0e01\u0e2a\u0e19\u0e38\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e22\u0e08\u0e23\u0e34\u0e07\u0e08\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u201c\u0e1e\u0e25\u0e34\u0e01\u0e42\u0e09\u0e21\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e2b\u0e47\u0e14\u0e43\u0e19\u0e16\u0e38\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48\u201d \u0e42\u0e14\u0e22 \u0e14\u0e23.\u0e2d\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e47\u0e14 \u0e2a\u0e32\u0e22\u0e01\u0e34\u0e19\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u201c\u0e19\u0e31\u0e01\u0e40\u0e01\u0e47\u0e15\u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a\u201d \u0e42\u0e14\u0e22 \u0e2d.\u0e19\u0e49\u0e33\u0e1d\u0e19 \u0e27\u0e07\u0e28\u0e4c\u0e04\u0e33\u0e0a\u0e31\u0e22 \u0e08\u0e32\u0e01\u0e2a\u0e27\u0e19\u0e2a\u0e2d\u0e07\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e08.\u0e40\u0e25\u0e22 \u0e2a\u0e32\u0e22\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u201c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\u201d \u0e42\u0e14\u0e22 \u0e2d.\u0e2a\u0e34\u0e23\u0e34\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e17\u0e2d\u0e07\u0e28\u0e34\u0e23\u0e34 \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e41\u0e08\u0e48\u0e21\u0e42\u0e2e\u0e21\u0e2a\u0e1b\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e04\u0e23\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u201c\u0e1b\u0e25\u0e39\u0e01\u2013\u0e1b\u0e23\u0e38\u0e07\u2013\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u201d \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07 \u201cSmart Farm\u201d \u0e04\u0e23\u0e1a\u0e08\u0e1a\u0e43\u0e19\u0e07\u0e32\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e27\u0e25\u0e32\u0e0a\u0e49\u0e2d\u0e1b \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e25\u0e32\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e19\u0e33 <strong>\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e27\u0e48\u0e32 100 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 <\/strong>\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32 \u201c\u0e02\u0e2d\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e19\u0e35\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01\u0e44\u0e2b\u0e19 \u0e43\u0e04\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e17\u0e33\u0e41\u0e25\u0e30\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e23\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e21\u0e32\u0e1a\u0e49\u0e32\u0e07 \u0e1a\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e08\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e08\u0e44\u0e14\u0e49\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e44\u0e14\u0e49\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e25\u0e2d\u0e07\u0e1b\u0e25\u0e39\u0e01 \u0e25\u0e2d\u0e07\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e47\u0e01 \u0e46\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e0a\u0e21 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c 3 \u0e21\u0e34\u0e15\u0e34 \u0e1f\u0e23\u0e35 \u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"764\" height=\"1080\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747279_0.jpg\" alt=\"\" class=\"wp-image-344890\" style=\"width:911px;height:auto\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e19\u0e35\u0e49 \u0e2d\u0e22\u0e32\u0e01\u0e0a\u0e27\u0e19\u0e17\u0e38\u0e01\u0e04\u0e19\u0e21\u0e32\u0e25\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28 \u0e21\u0e32\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2d\u0e32\u0e22\u0e27\u0e34\u0e16\u0e35\u0e17\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e07\u0e0a\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e08\u0e32\u0e01\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e2b\u0e2d\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e01\u0e27\u0e31\u0e19 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e15\u0e25\u0e32\u0e14\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u201c\u0e2a\u0e35\u0e2a\u0e31\u0e19 \u0e25\u0e35\u0e25\u0e32 \u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e07\u201d 5\u20136 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 08.00\u201317.00 \u0e19.\u0e13 \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e42\u0e17\u0e23 02-529-2212-13 \u0e41\u0e25\u0e30 087-359-7171 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c Facebook \u0e41\u0e25\u0e30 YouTube \u0e02\u0e2d\u0e07\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e02\u0e49\u0e32\u0e1f\u0e23\u0e35 \u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e49\u0e2d\u0e1b \u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u2014 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1e\u0e1a\u0e27\u0e48\u0e32 \u201c\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e07\u201d \u0e2a\u0e19\u0e38\u0e01\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e2d\u0e30\u0e44\u0e23\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e04\u0e34\u0e14<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747289_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344889\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747289_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747289_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747289_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747289_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747286_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344900\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747286_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747286_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747286_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747286_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747291_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344901\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747291_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747291_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747291_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747291_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747288_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344897\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747288_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747288_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747288_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747288_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747285_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344891\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747285_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747285_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747285_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747285_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747290_0-1200x800.jpg\" alt=\"\" class=\"wp-image-344894\" srcset=\"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747290_0-1200x800.jpg 1200w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747290_0-768x512.jpg 768w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747290_0-1536x1024.jpg 1536w, https:\/\/www.khaosod.co.th\/technologychaoban\/wp-content\/uploads\/2026\/09\/747290_0.jpg 1566w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e43\u0e04\u0e23\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32 \u201c\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u201d \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e41\u0e04\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e1c\u0e31\u0e01 \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e14\u0e39\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e49\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e19\u0e35\u0e49 \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e22\u0e01\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e19\u0e1a\u0e17\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e21\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19 \u0e15\u0e25\u0e32\u0e14\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u201c\u0e2a\u0e35\u0e2a\u0e31\u0e19 \u0e25\u0e35\u0e25\u0e32 \u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e07\u201d \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5\u20136 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569 \u0e40\u0e27\u0e25\u0e32 08.00\u201317.00 \u0e19. \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e16\u0e49\u0e32\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e15\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e23\u0e31\u0e01\u0e27\u0e34\u0e16\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23\u201d \u0e01\u0e47\u0e04\u0e07\u0e44\u0e21\u0e48\u0e1c\u0e34\u0e14\u0e19\u0e31\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e0a\u0e49\u0e2d\u0e1b\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e14\u0e35\u0e08\u0e32\u0e01\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e08\u0e23\u0e34\u0e07 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e32\u0e2d\u0e48\u0e32\u0e19\u0e08\u0e32\u0e01\u0e15\u0e33\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e1e\u0e31\u0e19\u0e08\u0e48\u0e32\u0e40\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 \u0e21\u0e32\u0e25\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2f \u0e40\u0e1c\u0e22\u0e16\u0e36\u0e07\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e27\u0e48\u0e32 \u201c\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e19\u0e33\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e08\u0e23\u0e34\u0e07\u0e21\u0e32\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e1a\u0e1b\u0e30 \u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e1e\u0e39\u0e14\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e04\u0e37\u0e2d \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e0a\u0e27\u0e19\u0e21\u0e32 \u201c\u0e14\u0e39\u0e40\u0e01\u0e29\u0e15\u0e23\u201d<\/p>\n","protected":false},"author":6,"featured_media":344899,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[20083,15773,4779,990],"msn":[],"line":[],"class_list":["post-344886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-techno-news","tag-20083","tag-15773","tag-4779","tag-990"],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/344886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/comments?post=344886"}],"version-history":[{"count":4,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/344886\/revisions"}],"predecessor-version":[{"id":344906,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/344886\/revisions\/344906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media\/344899"}],"wp:attachment":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media?parent=344886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/categories?post=344886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags?post=344886"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/msn?post=344886"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/line?post=344886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}