{"id":56687,"date":"2018-04-27T10:05:33","date_gmt":"2018-04-27T03:05:33","guid":{"rendered":"https:\/\/www.technologychaoban.com\/?p=56687"},"modified":"2018-04-27T10:44:33","modified_gmt":"2018-04-27T03:44:33","slug":"2-%e0%b9%82%e0%b8%88%e0%b8%a3%e0%b9%81%e0%b8%aa%e0%b8%9a-%e0%b9%81%e0%b8%ad%e0%b8%9a%e0%b8%82%e0%b9%82%e0%b8%a1%e0%b8%a2%e0%b8%95%e0%b8%b1%e0%b8%94%e0%b8%9c%e0%b8%a5%e0%b8%9b%e0%b8%b2%e0%b8%a5","status":"publish","type":"post","link":"https:\/\/www.khaosod.co.th\/technologychaoban\/techno-news\/article_56687","title":{"rendered":"2 \u0e42\u0e08\u0e23\u0e41\u0e2a\u0e1a \u0e41\u0e2d\u0e1a\u0e02\u0e42\u0e21\u0e22\u0e15\u0e31\u0e14\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e01\u0e27\u0e48\u0e32 10 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e19 \u0e14\u0e31\u0e01\u0e0b\u0e38\u0e48\u0e21 \u2018\u0e2d\u0e36\u0e49\u0e07\u2019 \u0e04\u0e19\u0e01\u0e31\u0e19\u0e40\u0e2d\u0e07"},"content":{"rendered":"<p>\u0e23.\u0e15.\u0e2d.\u0e21\u0e13\u0e11\u0e25 \u0e17\u0e2d\u0e07\u0e21\u0e32 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e27\u0e23\u0e2a\u0e2d\u0e1a\u0e2a\u0e27\u0e19 \u0e2a\u0e20.\u0e04\u0e25\u0e2d\u0e07\u0e17\u0e48\u0e2d\u0e21 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e33\u0e23\u0e27\u0e08\u0e2a\u0e32\u0e22\u0e15\u0e23\u0e27\u0e08 \u0e15.\u0e1e\u0e23\u0e38\u0e14\u0e34\u0e19\u0e19\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e02\u0e2d\u0e07 \u0e19\u0e32\u0e22\u0e2d\u0e34\u0e1a\u0e23\u0e2d\u0e2b\u0e35\u0e21 \u0e1a\u0e37\u0e2d\u0e41\u0e19 \u0e2d\u0e32\u0e22\u0e38 41 \u0e1b\u0e35 \u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19 \u0e15.\u0e1e\u0e23\u0e38\u0e14\u0e34\u0e19\u0e19\u0e32 \u0e2d.\u0e04\u0e25\u0e2d\u0e07\u0e17\u0e48\u0e2d\u0e21 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u0e2b\u0e25\u0e31\u0e07\u0e23\u0e31\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e27\u0e48\u0e32 \u0e16\u0e39\u0e01\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e04\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e02\u0e42\u0e21\u0e22\u0e15\u0e31\u0e14\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e02\u0e13\u0e30\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e0a\u0e38\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e25\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e1a\u0e15\u0e31\u0e27 \u0e41\u0e15\u0e48\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e27\u0e34\u0e48\u0e07\u0e2b\u0e25\u0e1a\u0e2b\u0e19\u0e35\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e17\u0e34\u0e49\u0e07\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e04\u0e35\u0e22\u0e27\u0e44\u0e27\u0e49 1 \u0e40\u0e25\u0e48\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1e\u0e1a\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e16\u0e39\u0e01\u0e15\u0e31\u0e14\u0e25\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e15\u0e49\u0e19 \u0e23\u0e27\u0e21\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,000 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 3,000 \u0e1a\u0e32\u0e17 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e36\u0e07\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19<br \/>\n<img decoding=\"async\" class=\"alignnone size-large wp-image-1012048\" src=\"https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53166-696x392.jpg\" sizes=\"(max-width: 696px) 100vw, 696px\" srcset=\"https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53166-696x392.jpg 696w, https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53166-300x169.jpg 300w, https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53166-768x432.jpg 768w, https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53166-1200x675.jpg 1200w, https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53166-746x420.jpg 746w\" alt=\"\" width=\"696\" height=\"392\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" \/><br \/>\n\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e27\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e15\u0e19\u0e1b\u0e25\u0e39\u0e01\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e19\u0e27\u0e19 60 \u0e44\u0e23\u0e48 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e16\u0e39\u0e01\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e02\u0e42\u0e21\u0e22 \u0e40\u0e01\u0e47\u0e1a\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e27\u0e48\u0e32 10 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e0b\u0e38\u0e48\u0e21\u0e14\u0e39 \u0e41\u0e25\u0e30\u0e1e\u0e1a\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e32\u0e22 2 \u0e04\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e02\u0e42\u0e21\u0e22\u0e15\u0e31\u0e14\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e2d\u0e35\u0e01 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e36\u0e07\u0e42\u0e17\u0e23.\u0e41\u0e08\u0e49\u0e07 \u0e0a\u0e38\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e25\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e1a \u0e41\u0e15\u0e48\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e27\u0e34\u0e48\u0e07\u0e2b\u0e25\u0e1a\u0e2b\u0e19\u0e35\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e15\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e2d\u0e2d\u0e01\u0e2b\u0e21\u0e32\u0e22\u0e08\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e21\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e44\u0e1b<br \/>\n<img decoding=\"async\" class=\"alignnone size-large wp-image-1012049\" src=\"https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53168-696x392.jpg\" sizes=\"(max-width: 696px) 100vw, 696px\" srcset=\"https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53168-696x392.jpg 696w, https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53168-300x169.jpg 300w, https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53168-768x432.jpg 768w, https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53168-1200x675.jpg 1200w, https:\/\/www.khaosod.co.th\/wp-content\/uploads\/2018\/04\/53168-746x420.jpg 746w\" alt=\"\" width=\"696\" height=\"392\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" \/><\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23.\u0e15.\u0e2d.\u0e21\u0e13\u0e11\u0e25 \u0e17\u0e2d\u0e07\u0e21\u0e32 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e27\u0e23\u0e2a\u0e2d\u0e1a\u0e2a\u0e27\u0e19 \u0e2a\u0e20.\u0e04\u0e25\u0e2d\u0e07\u0e17\u0e48\u0e2d\u0e21 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e33\u0e23\u0e27\u0e08\u0e2a\u0e32\u0e22\u0e15\u0e23\u0e27\u0e08 \u0e15.\u0e1e\u0e23\u0e38\u0e14\u0e34\u0e19\u0e19\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e02\u0e2d\u0e07 \u0e19\u0e32\u0e22\u0e2d\u0e34\u0e1a\u0e23\u0e2d\u0e2b\u0e35\u0e21 \u0e1a\u0e37\u0e2d\u0e41\u0e19 \u0e2d\u0e32\u0e22\u0e38 41 \u0e1b\u0e35 \u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19 \u0e15.\u0e1e\u0e23\u0e38\u0e14\u0e34\u0e19\u0e19\u0e32 \u0e2d.\u0e04\u0e25\u0e2d\u0e07\u0e17\u0e48\u0e2d\u0e21 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u0e2b\u0e25\u0e31\u0e07\u0e23\u0e31\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e27\u0e48\u0e32 \u0e16\u0e39\u0e01\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e04\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e02\u0e42\u0e21\u0e22\u0e15\u0e31\u0e14\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e02\u0e13\u0e30\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e0a\u0e38\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e25\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e1a\u0e15\u0e31\u0e27 \u0e41\u0e15\u0e48\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e27\u0e34\u0e48\u0e07\u0e2b\u0e25\u0e1a\u0e2b\u0e19\u0e35\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e17\u0e34\u0e49\u0e07\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e04\u0e35\u0e22\u0e27\u0e44\u0e27\u0e49 1 \u0e40\u0e25\u0e48\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1e\u0e1a\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e16\u0e39\u0e01\u0e15\u0e31\u0e14\u0e25\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e15\u0e49\u0e19 \u0e23\u0e27\u0e21\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,000 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 3,000 \u0e1a\u0e32\u0e17 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e36\u0e07\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19 \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e27\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e15\u0e19\u0e1b\u0e25\u0e39\u0e01\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e19\u0e27\u0e19 60 \u0e44\u0e23\u0e48 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e16\u0e39\u0e01\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e02\u0e42\u0e21\u0e22 \u0e40\u0e01\u0e47\u0e1a\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e27\u0e48\u0e32 10 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e0b\u0e38\u0e48\u0e21\u0e14\u0e39 \u0e41\u0e25\u0e30\u0e1e\u0e1a\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e32\u0e22 2 \u0e04\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e02\u0e42\u0e21\u0e22\u0e15\u0e31\u0e14\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e2d\u0e35\u0e01 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e36\u0e07\u0e42\u0e17\u0e23.\u0e41\u0e08\u0e49\u0e07 \u0e0a\u0e38\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e1a\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e25\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e1a \u0e41\u0e15\u0e48\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e27\u0e34\u0e48\u0e07\u0e2b\u0e25\u0e1a\u0e2b\u0e19\u0e35\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e15\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e2d\u0e2d\u0e01\u0e2b\u0e21\u0e32\u0e22\u0e08\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e49\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e21\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e17\u0e35\u0e48\u0e21\u0e32 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c<\/p>\n","protected":false},"author":5,"featured_media":56688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9901,1529],"msn":[],"line":[],"class_list":["post-56687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-techno-news","tag-9901","tag-1529"],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/56687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/comments?post=56687"}],"version-history":[{"count":0,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts\/56687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media\/56688"}],"wp:attachment":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/media?parent=56687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/categories?post=56687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags?post=56687"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/msn?post=56687"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/line?post=56687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}