{"id":11647,"count":4,"description":"","link":"https:\/\/www.khaosod.co.th\/technologychaoban\/tag\/%e0%b8%9e%e0%b8%b7%e0%b8%8a%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99","name":"\u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e1a\u0e49\u0e32\u0e19","slug":"%e0%b8%9e%e0%b8%b7%e0%b8%8a%e0%b8%9c%e0%b8%b1%e0%b8%81%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags\/11647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts?tags=11647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}