{"id":43828,"count":1,"description":"","link":"https:\/\/www.khaosod.co.th\/technologychaoban\/tag\/%e0%b9%84%e0%b8%82%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%ab%e0%b8%a1%e0%b8%ad%e0%b8%84%e0%b8%b2%e0%b8%87%e0%b8%94%e0%b8%b3","name":"\u0e44\u0e02\u0e48\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e2d\u0e04\u0e32\u0e07\u0e14\u0e33","slug":"%e0%b9%84%e0%b8%82%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%ab%e0%b8%a1%e0%b8%ad%e0%b8%84%e0%b8%b2%e0%b8%87%e0%b8%94%e0%b8%b3","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags\/43828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts?tags=43828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}