{"id":46707,"count":1,"description":"","link":"https:\/\/www.khaosod.co.th\/technologychaoban\/tag\/%e0%b8%ad%e0%b8%b3%e0%b9%80%e0%b8%a0%e0%b8%ad%e0%b8%9b%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%81%e0%b8%a3%e0%b9%87%e0%b8%94","name":"\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1b\u0e32\u0e01\u0e40\u0e01\u0e23\u0e47\u0e14","slug":"%e0%b8%ad%e0%b8%b3%e0%b9%80%e0%b8%a0%e0%b8%ad%e0%b8%9b%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%81%e0%b8%a3%e0%b9%87%e0%b8%94","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags\/46707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.khaosod.co.th\/technologychaoban\/wp-json\/wp\/v2\/posts?tags=46707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}